{"id":3764,"date":"2022-10-24T22:08:44","date_gmt":"2022-10-24T22:08:44","guid":{"rendered":"https:\/\/www.adventdesk.com\/home\/?p=3764"},"modified":"2022-10-26T21:54:17","modified_gmt":"2022-10-26T21:54:17","slug":"foi-et-priere","status":"publish","type":"post","link":"https:\/\/www.adventdesk.com\/home\/foi-et-priere\/","title":{"rendered":"Foi et pri\u00e8re"},"content":{"rendered":"<h3 id=\"1692\" class=\"egw_content_wrapper egw-selected-paragraph\" data-para-id=\"87.1692\" data-refcode=\"Pr 314\"><span class=\"egw_content\" data-refcode=\"87.1692\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1701&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 314&quot;},{&quot;para_id&quot;:&quot;1765.2183&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 371&quot;},{&quot;para_id&quot;:&quot;2689.1673&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 314&quot;},{&quot;para_id&quot;:&quot;1871.1675&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 314&quot;}]\" data-refcode-old=\"Pr 314\"><span class=\"\">Chapitre 32 \u2014 Foi et pri\u00e8re<\/span><\/span><\/h3>\n<p id=\"1693\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1693\" data-refcode=\"Pr 314.1\"><span class=\"egw_content\" data-refcode=\"87.1693\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2184&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 371.1&quot;},{&quot;para_id&quot;:&quot;190.1702&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 314.1&quot;},{&quot;para_id&quot;:&quot;2689.1674&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 314.1&quot;},{&quot;para_id&quot;:&quot;1871.1676&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 314.1&quot;}]\" data-refcode-old=\"Pr 314.1\">La foi, c&rsquo;est faire confiance \u00e0 Dieu, croire qu&rsquo;il nous aime et qu&rsquo;il sait mieux ce qui est pour notre bien.\u00a0Ainsi, au lieu de la n\u00f4tre, cela nous am\u00e8ne \u00e0 choisir sa voie.\u00a0Au lieu de notre ignorance, il accepte sa sagesse ;\u00a0\u00e0 la place de notre faiblesse, Sa force ;\u00a0\u00e0 la place de notre p\u00e9ch\u00e9, Sa justice.\u00a0Nos vies, nous-m\u00eames, sont d\u00e9j\u00e0 siennes ;\u00a0la foi reconna\u00eet sa propri\u00e9t\u00e9 et accepte sa b\u00e9n\u00e9diction.\u00a0La v\u00e9rit\u00e9, la droiture, la puret\u00e9 ont \u00e9t\u00e9 d\u00e9sign\u00e9es comme les secrets du succ\u00e8s de la vie.\u00a0C&rsquo;est la foi qui nous met en possession de ces principes.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 314.1 (Ellen Gould White)\">Pr 314.1<\/span><\/p>\n<p data-para-id=\"87.1693\" data-refcode=\"Pr 314.1\"><!--more--><\/p>\n<p id=\"1694\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1694\" data-refcode=\"Pr 314.2\"><span class=\"egw_content\" data-refcode=\"87.1694\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1703&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 314.2&quot;},{&quot;para_id&quot;:&quot;1765.2185&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 371.2&quot;},{&quot;para_id&quot;:&quot;2689.1675&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 314.2&quot;},{&quot;para_id&quot;:&quot;1871.1677&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 314.2&quot;}]\" data-refcode-old=\"Pr 314.2\">Toute bonne impulsion ou aspiration est le don de Dieu ;\u00a0la foi re\u00e7oit de Dieu la vie qui seule peut produire une vraie croissance et efficacit\u00e9.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 314.2 (Ellen Gould White)\">Pr 314.2<\/span><\/p>\n<p id=\"1695\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1695\" data-refcode=\"Pr 314.3\"><span class=\"egw_content\" data-refcode=\"87.1695\" data-translate=\"[{&quot;para_id&quot;:&quot;2729.348&quot;,&quot;lang&quot;:&quot;de&quot;,&quot;refcode&quot;:&quot;DG 71.3&quot;},{&quot;para_id&quot;:&quot;1765.2187&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 372.1&quot;},{&quot;para_id&quot;:&quot;190.1704&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 314.3&quot;},{&quot;para_id&quot;:&quot;2689.1676&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 314.3&quot;},{&quot;para_id&quot;:&quot;1871.1677&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 314.2&quot;}]\" data-refcode-old=\"Pr 314.3\">La fa\u00e7on d&rsquo;exercer la foi devrait \u00eatre rendue tr\u00e8s claire.\u00a0\u00c0 chaque promesse de Dieu, il y a des conditions.\u00a0Si nous sommes dispos\u00e9s \u00e0 faire sa volont\u00e9, toute sa force est n\u00f4tre.\u00a0Quel que soit le don qu&rsquo;Il promet, c&rsquo;est dans la promesse elle-m\u00eame.\u00a0\u00ab\u00a0La semence est la parole de Dieu.\u00a0\u00bb\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.51538#51538\" data-link=\"1965.51538\">Luc 8:11<\/a>\u00a0.\u00a0Aussi s\u00fbrement que le ch\u00eane est dans le gland, ainsi est s\u00fbrement le don de Dieu dans Sa promesse.\u00a0Si nous recevons la promesse, nous avons le don.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 314.3 (Ellen Gould White)\">Pr 314.3<\/span><\/p>\n<p id=\"1696\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1696\" data-refcode=\"Pr 314.4\"><span class=\"egw_content\" data-refcode=\"87.1696\" data-translate=\"[{&quot;para_id&quot;:&quot;2729.338&quot;,&quot;lang&quot;:&quot;de&quot;,&quot;refcode&quot;:&quot;DG 69.4&quot;},{&quot;para_id&quot;:&quot;1765.2188&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 372.2&quot;},{&quot;para_id&quot;:&quot;190.1705&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 314.4&quot;},{&quot;para_id&quot;:&quot;2689.1677&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 314.4&quot;},{&quot;para_id&quot;:&quot;1871.1678&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 314.3&quot;}]\" data-refcode-old=\"Pr 314.4\">La foi qui nous permet de recevoir les dons de Dieu est elle-m\u00eame un don dont une certaine mesure est transmise \u00e0 chaque \u00eatre humain.\u00a0\u00c7a granditcomme exerc\u00e9 \u00e0 s&rsquo;approprier la parole de Dieu.\u00a0Pour fortifier la foi, il faut souvent la mettre en contact avec la parole.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 314.4 (Ellen Gould White)\">Pr 314.4<\/span><\/p>\n<p id=\"1699\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1699\" data-refcode=\"Pr 315.1\"><span class=\"egw_content\" data-refcode=\"87.1699\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2189&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 372.3&quot;},{&quot;para_id&quot;:&quot;190.1708&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 315.1&quot;},{&quot;para_id&quot;:&quot;2689.1680&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 315.1&quot;},{&quot;para_id&quot;:&quot;1871.1681&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 315.1&quot;}]\" data-refcode-old=\"Pr 315.1\">Dans l&rsquo;\u00e9tude de la Bible, l&rsquo;\u00e9tudiant doit \u00eatre amen\u00e9 \u00e0 voir la puissance de la parole de Dieu.\u00a0Dans la cr\u00e9ation, \u00ab Il a parl\u00e9, et cela a \u00e9t\u00e9 fait ;\u00a0Il a command\u00e9, et cela a tenu bon.\u00a0Il \u00ab appelle les choses qui ne sont pas comme si elles \u00e9taient \u00bb (\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.29283#29283\" data-link=\"1965.29283\">Psaume 33\u00a0:9<\/a>\u00a0;\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.57176#57176\" data-link=\"1965.57176\">Romains 4\u00a0:17<\/a>\u00a0) ;\u00a0car quand Il les appelle, ils sont.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 315.1 (Ellen Gould White)\">Pr 315.1<\/span><\/p>\n<p id=\"1700\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1700\" data-refcode=\"Pr 315.2\"><span class=\"egw_content\" data-refcode=\"87.1700\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2190&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 372.4&quot;},{&quot;para_id&quot;:&quot;190.1709&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 315.2&quot;},{&quot;para_id&quot;:&quot;2689.1681&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 315.2&quot;},{&quot;para_id&quot;:&quot;1871.1682&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 315.2&quot;}]\" data-refcode-old=\"Pr 315.2\">Combien de fois ceux qui ont fait confiance \u00e0 la parole de Dieu, bien qu&rsquo;en eux-m\u00eames totalement impuissants, ont r\u00e9sist\u00e9 \u00e0 la puissance du monde entier &#8211; \u00c9noch, pur de c\u0153ur, saint dans la vie, tenant fermement sa foi dans le triomphe de la justice contre une g\u00e9n\u00e9ration corrompue et moqueuse ;\u00a0No\u00e9 et sa maison contre les hommes de son temps, les hommes de la plus grande force physique et mentale et les plus avilis en morale ;\u00a0les enfants d&rsquo;Isra\u00ebl \u00e0 la mer Rouge, une multitude d&rsquo;esclaves impuissants et terrifi\u00e9s, contre l&rsquo;arm\u00e9e la plus puissante de la nation la plus puissante du globe;\u00a0David, un jeune berger, ayant la promesse de Dieu du tr\u00f4ne, contre Sa\u00fcl, le monarque \u00e9tabli, d\u00e9termin\u00e9 \u00e0 maintenir son pouvoir;\u00a0Shadrach et ses compagnons dans le feu, et Nebucadnetsar sur le tr\u00f4ne ;\u00a0Daniel parmi les lions, ses ennemis dans les hauts lieux du royaume ;\u00a0J\u00e9sus sur la croix,\u00a0et les pr\u00eatres et dirigeants juifs for\u00e7ant m\u00eame le gouverneur romain \u00e0 accomplir leur volont\u00e9 ;\u00a0Paul encha\u00een\u00e9 a conduit \u00e0 la mort d&rsquo;un criminel, N\u00e9ron le despote d&rsquo;un empire mondial.<\/span>\u00a0<span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 315.2 (Ellen Gould White)\">Pr 315.2<\/span><\/p>\n<p id=\"1701\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1701\" data-refcode=\"Pr 315.3\"><span class=\"egw_content\" data-refcode=\"87.1701\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1710&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 315.3&quot;},{&quot;para_id&quot;:&quot;1765.2192&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 373.1&quot;},{&quot;para_id&quot;:&quot;2689.1682&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 315.3&quot;},{&quot;para_id&quot;:&quot;1871.1683&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 315.3&quot;}]\" data-refcode-old=\"Pr 315.3\">De tels exemples ne se trouvent pas seulement dans la Bible.\u00a0Ils abondent dans tous les registres du progr\u00e8s humain.\u00a0Les Vaudois et les Huguenots, Wycliffe et Huss, J\u00e9r\u00f4me et Luther, Tyndale et Knox, Zinzendorf et Wesley, avec des multitudes d&rsquo;autres, ont t\u00e9moign\u00e9 de la puissance de la parole de Dieu contre la puissance et la politique humaines en faveur du mal.\u00a0Ce sont la vraie noblesse du monde.\u00a0C&rsquo;est sa lign\u00e9e royale.\u00a0Dans cette ligne, les jeunes d&rsquo;aujourd&rsquo;hui sont appel\u00e9s \u00e0 prendre leur place.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 315.3 (Ellen Gould White)\">Pr 315.3<\/span><\/p>\n<p id=\"1702\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1702\" data-refcode=\"Pr 315.4\"><span class=\"egw_content\" data-refcode=\"87.1702\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1711&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 315.4&quot;},{&quot;para_id&quot;:&quot;1765.2193&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 373.2&quot;},{&quot;para_id&quot;:&quot;2689.1683&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 315.4&quot;},{&quot;para_id&quot;:&quot;1871.1684&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 315.4&quot;}]\" data-refcode-old=\"Pr 315.4\">La foi est n\u00e9cessaire dans les petites affaires non moins que dans les grandes affaires de la vie.\u00a0Dans tous nos int\u00e9r\u00eats et nos occupations quotidiennes, la force de soutien de Dieu devient r\u00e9elle pour nous gr\u00e2ce \u00e0 une confiance in\u00e9branlable.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 315.4 (Ellen Gould White)\">Pr 315.4<\/span><\/p>\n<p id=\"1703\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1703\" data-refcode=\"Pr 315.5\"><span class=\"egw_content\" data-refcode=\"87.1703\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1713&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 316.1&quot;},{&quot;para_id&quot;:&quot;1765.2194&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 373.3&quot;},{&quot;para_id&quot;:&quot;2689.1684&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 315.5&quot;},{&quot;para_id&quot;:&quot;1871.1685&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 315.5&quot;}]\" data-refcode-old=\"Pr 315.5\">Vue sous son aspect humain, la vie est pour tous un chemin in\u00e9dit.\u00a0C&rsquo;est un chemin dans lequel, en ce qui concerne nos exp\u00e9riences plus profondes, nous marchons chacunseul.\u00a0Dans notre vie int\u00e9rieure, aucun autre \u00eatre humain ne peut entrer pleinement.\u00a0Alors que le petit enfant entreprend ce voyage dans lequel, t\u00f4t ou tard, il doit choisir son propre chemin, d\u00e9cidant lui-m\u00eame des probl\u00e8mes de la vie pour l&rsquo;\u00e9ternit\u00e9, combien s\u00e9rieux devrait \u00eatre l&rsquo;effort de diriger sa confiance vers le s\u00fbr Guide et Aide !\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 315,5 (Ellen Gould White)\">Pr 315,5<\/span><\/p>\n<p id=\"1706\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1706\" data-refcode=\"Pr 316.1\"><span class=\"egw_content\" data-refcode=\"87.1706\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1714&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 316.2&quot;},{&quot;para_id&quot;:&quot;1765.2195&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 373.4&quot;},{&quot;para_id&quot;:&quot;2689.1687&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 316.1&quot;},{&quot;para_id&quot;:&quot;1871.1685&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 315.5&quot;}]\" data-refcode-old=\"Pr 316.1\">En tant que bouclier contre la tentation et source d&rsquo;inspiration vers la puret\u00e9 et la v\u00e9rit\u00e9, aucune autre influence ne peut \u00e9galer le sentiment de la pr\u00e9sence de Dieu.\u00a0\u00ab\u00a0Toutes choses sont nues et d\u00e9couvertes aux yeux de Celui \u00e0 qui nous avons affaire.\u00a0\u00bb\u00a0Il a \u00a0\u00bb des yeux plus purs que pour voir le mal, et ne peut pas regarder l&rsquo;iniquit\u00e9 \u00ab\u00a0.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.61252#61252\" data-link=\"1965.61252\">H\u00e9breux 4:13<\/a>\u00a0;\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.46430#46430\" data-link=\"1965.46430\">Habakuk 1:13<\/a>\u00a0.\u00a0Cette pens\u00e9e \u00e9tait le bouclier de Joseph au milieu des corruptions de l&rsquo;\u00c9gypte.\u00a0Aux attraits de la tentation, sa r\u00e9ponse fut ferme : \u00ab Comment&#8230; puis-je faire ce grand mal et p\u00e9cher contre Dieu ?\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.2359#2359\" data-link=\"1965.2359\">Gen\u00e8se 39:9<\/a>\u00a0.\u00a0Un tel bouclier, la foi, si elle est ch\u00e9rie, l&rsquo;apportera \u00e0 chaque \u00e2me.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 316.1 (Ellen Gould White)\">Pr 316.1<\/span><\/p>\n<p id=\"1707\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1707\" data-refcode=\"Pr 316.2\"><span class=\"egw_content\" data-refcode=\"87.1707\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1715&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 316.3&quot;},{&quot;para_id&quot;:&quot;1765.2196&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 373.5&quot;},{&quot;para_id&quot;:&quot;2689.1689&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 316.2&quot;},{&quot;para_id&quot;:&quot;1871.1688&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 316.1&quot;}]\" data-refcode-old=\"Pr 316.2\">Seul le sentiment de la pr\u00e9sence de Dieu peut chasser la peur qui, pour l&rsquo;enfant timide, ferait de la vie un fardeau.\u00a0Qu&rsquo;il fixe dans sa m\u00e9moire la promesse : \u00ab L&rsquo;ange du Seigneur campe autour de ceux qui le craignent et les d\u00e9livre.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.29324#29324\" data-link=\"1965.29324\">Psaume 34:7<\/a>.\u00a0Qu&rsquo;il lise cette merveilleuse histoire d&rsquo;Elis\u00e9e dans la ville de montagne, et, entre lui et les arm\u00e9es d&rsquo;ennemis arm\u00e9s, une puissante bande d&rsquo;anges c\u00e9lestes.\u00a0Qu&rsquo;il lise comment \u00e0 Pierre, en prison et condamn\u00e9 \u00e0 mort, l&rsquo;ange de Dieu est apparu ;\u00a0comment, pass\u00e9 les gardes arm\u00e9s, les portes massives et le grand portail de fer avec leurs verrous et leurs barreaux, l&rsquo;ange conduisit le serviteur de Dieu en toute s\u00e9curit\u00e9.\u00a0Qu&rsquo;il lise cette sc\u00e8ne sur la mer, lorsque les soldats et les marins secou\u00e9s par la temp\u00eate, \u00e9puis\u00e9s par le travail, la surveillance et le long je\u00fbne, Paul le prisonnier, en route pour le proc\u00e8s et l&rsquo;ex\u00e9cution, prononc\u00e8rent ces grandes paroles de courage et d&rsquo;espoir : \u00ab Ayez bon courage, car il n&rsquo;y aura pas de perte de la vie d&rsquo;un homme parmi vous&#8230; Car il s&rsquo;est tenu pr\u00e8s de moi cette nuit l&rsquo;ange de Dieu, \u00e0 qui je suis et que je sers, disant : Paul, ne crains pas ;\u00a0tu dois \u00eatre amen\u00e9 devant C\u00e9sar : et voici,\u00a0Dieu t&rsquo;a donn\u00e9 tous ceux qui naviguent avec toi.\u00a0Dans la foi de cette promesse, Paul a assur\u00e9 \u00e0 ses compagnons : \u00ab Il ne tombera pas un cheveu de la t\u00eate d&rsquo;aucun de vous.\u00a0Alors c&rsquo;est arriv\u00e9.\u00a0Parce qu&rsquo;il y avait dans ce navire un homme par qui Dieu pouvait travailler, toute la cargaisonde soldats et de marins pa\u00efens a \u00e9t\u00e9 pr\u00e9serv\u00e9.\u00a0\u00ab\u00a0Ils se sont \u00e9chapp\u00e9s en toute s\u00e9curit\u00e9 pour atterrir.\u00a0\u00bb\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.56846#56846\" data-link=\"1965.56846\">Actes 27:22-24, 34, 44<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 316.2 (Ellen Gould White)\">Pr 316.2<\/span><\/p>\n<p id=\"1710\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1710\" data-refcode=\"Pr 317.1\"><span class=\"egw_content\" data-refcode=\"87.1710\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2199&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 374.1&quot;},{&quot;para_id&quot;:&quot;190.1718&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.1&quot;},{&quot;para_id&quot;:&quot;2689.1692&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.1&quot;},{&quot;para_id&quot;:&quot;1871.1691&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.1&quot;}]\" data-refcode-old=\"Pr 317.1\">Ces choses n&rsquo;ont pas \u00e9t\u00e9 \u00e9crites simplement pour que nous puissions les lire et nous \u00e9merveiller, mais pour que la m\u00eame foi qui a op\u00e9r\u00e9 dans les anciens serviteurs de Dieu puisse agir en nous.\u00a0D&rsquo;une mani\u00e8re non moins marqu\u00e9e que celle qu&rsquo;il a alors op\u00e9r\u00e9e, il agira maintenant partout o\u00f9 il y a des c\u0153urs de foi pour \u00eatre les canaux de sa puissance.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317.1 (Ellen Gould White)\">Pr 317.1<\/span><\/p>\n<p id=\"1711\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1711\" data-refcode=\"Pr 317.2\"><span class=\"egw_content\" data-refcode=\"87.1711\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2200&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 374.2&quot;},{&quot;para_id&quot;:&quot;190.1719&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.2&quot;},{&quot;para_id&quot;:&quot;2689.1693&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.2&quot;},{&quot;para_id&quot;:&quot;1871.1692&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.2&quot;}]\" data-refcode-old=\"Pr 317.2\">Que ceux qui se m\u00e9fient d&rsquo;eux-m\u00eames, dont le manque d&rsquo;autonomie les am\u00e8ne \u00e0 reculer devant les soins et la responsabilit\u00e9, apprennent \u00e0 se fier \u00e0 Dieu.\u00a0Ainsi, beaucoup de ceux qui autrement ne seraient qu&rsquo;un chiffre dans le monde, peut-\u00eatre seulement un fardeau impuissant, pourront dire avec l&rsquo;ap\u00f4tre Paul : \u00ab Je puis tout par Christ qui me fortifie.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.60070#60070\" data-link=\"1965.60070\">Philippiens 4:13<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317.2 (Ellen Gould White)\">Pr 317.2<\/span><\/p>\n<p id=\"1712\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1712\" data-refcode=\"Pr 317.3\"><span class=\"egw_content\" data-refcode=\"87.1712\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1719&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.2&quot;},{&quot;para_id&quot;:&quot;1765.2200&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 374.2&quot;},{&quot;para_id&quot;:&quot;2689.1694&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.3&quot;},{&quot;para_id&quot;:&quot;1871.1693&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.3&quot;}]\" data-refcode-old=\"Pr 317.3\">Pour l&rsquo;enfant aussi qui est prompt \u00e0 ressentir les blessures, la foi a de pr\u00e9cieuses le\u00e7ons.\u00a0La disposition \u00e0 r\u00e9sister au mal ou \u00e0 venger le mal est souvent motiv\u00e9e par un sens aigu de la justice et un esprit actif et \u00e9nergique.\u00a0Qu&rsquo;un tel enfant apprenne que Dieu est le gardien \u00e9ternel du droit.\u00a0Il a une tendre sollicitude pour les \u00eatres qu&rsquo;il a tant aim\u00e9s qu&rsquo;il a donn\u00e9 le salut \u00e0 son bien-aim\u00e9.\u00a0Il s&rsquo;occupera de chaque malfaiteur.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317.3 (Ellen Gould White)\">Pr 317.3<\/span><\/p>\n<p id=\"1713\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1713\" data-refcode=\"Pr 317.4\"><span class=\"egw_content\" data-refcode=\"87.1713\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1719&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.2&quot;},{&quot;para_id&quot;:&quot;1765.2203&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.1&quot;},{&quot;para_id&quot;:&quot;2689.1695&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.4&quot;},{&quot;para_id&quot;:&quot;1871.1694&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.4&quot;}]\" data-refcode-old=\"Pr 317.4\">\u00ab\u00a0Car celui qui vous touche touche la prunelle de ses yeux.\u00a0\u00bb\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.46768#46768\" data-link=\"1965.46768\">Zacharie 2:8<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317.4 (Ellen Gould White)\">Pr 317.4<\/span><\/p>\n<p id=\"1714\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1714\" data-refcode=\"Pr 317.5\"><span class=\"egw_content\" data-refcode=\"87.1714\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1719&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.2&quot;},{&quot;para_id&quot;:&quot;1765.2204&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.2&quot;},{&quot;para_id&quot;:&quot;2689.1696&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.5&quot;},{&quot;para_id&quot;:&quot;1871.1695&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.5&quot;}]\" data-refcode-old=\"Pr 317.5\">\u00ab Recommande ta voie au Seigneur ;\u00a0ayez aussi confiance en Lui;\u00a0et il l&rsquo;accomplira&#8230; Il fera para\u00eetre ta justice comme la lumi\u00e8re, et ton jugement comme le midi.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.29447#29447\" data-link=\"1965.29447\">Psaume 37:5, 6<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317,5 (Ellen Gould White)\">Pr 317.5<\/span><\/p>\n<p id=\"1715\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1715\" data-refcode=\"Pr 317.6\"><span class=\"egw_content\" data-refcode=\"87.1715\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2205&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.3&quot;},{&quot;para_id&quot;:&quot;190.1722&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.3&quot;},{&quot;para_id&quot;:&quot;2689.1697&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.6&quot;},{&quot;para_id&quot;:&quot;1871.1696&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.6&quot;}]\" data-refcode-old=\"Pr 317.6\">\u00ab Le Seigneur sera aussi un refuge pour les opprim\u00e9s, un refuge dans les temps de d\u00e9tresse.\u00a0Et ceux qui connaissent ton nom mettront leur confiance en toi, car toi, Seigneur, tu n&rsquo;as pas abandonn\u00e9 ceux qui te cherchent.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.28569#28569\" data-link=\"1965.28569\">Psaume 9:9, 10<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317.6 (Ellen Gould White)\">Pr 317.6<\/span><\/p>\n<p id=\"1716\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1716\" data-refcode=\"Pr 317.7\"><span class=\"egw_content\" data-refcode=\"87.1716\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1723&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 317.4&quot;},{&quot;para_id&quot;:&quot;1765.2206&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.4&quot;},{&quot;para_id&quot;:&quot;2689.1698&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 317.7&quot;},{&quot;para_id&quot;:&quot;1871.1697&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 317.7&quot;}]\" data-refcode-old=\"Pr 317.7\">La compassion que Dieu manifeste envers nous, Il nous demande de la manifester envers les autres.\u00a0Que l&rsquo;impulsif, l&rsquo;autosuffisant, le vengeur, voici le doux et l&rsquo;humble, men\u00e9 comme un agneau \u00e0 l&rsquo;abattoir, sans repr\u00e9sailles comme une brebis muette devant ses tondeurs.\u00a0Qu&rsquo;ils regardent celui que nos p\u00e9ch\u00e9s ont transperc\u00e9 et que nos douleurs ont accabl\u00e9, et ils apprendront \u00e0 endurer, \u00e0 s&rsquo;abstenir et \u00e0 pardonner.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 317,7 (Ellen Gould White)\">Pr 317.7<\/span><\/p>\n<p id=\"1718\" class=\"egw_content_wrapper standard-noindent\" data-para-id=\"87.1718\" data-refcode=\"Pr 318.1\"><span class=\"egw_content\" data-refcode=\"87.1718\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1725&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.1&quot;},{&quot;para_id&quot;:&quot;1765.2207&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.5&quot;},{&quot;para_id&quot;:&quot;2689.1700&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.1&quot;},{&quot;para_id&quot;:&quot;1871.1699&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.1&quot;}]\" data-refcode-old=\"Pr 318.1\">Par la foi en Christ, chaque d\u00e9ficience de caract\u00e8re peut \u00eatre combl\u00e9e, chaque souillure nettoy\u00e9e, chaque faute corrig\u00e9e, chaque excellence d\u00e9velopp\u00e9e.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318.1 (Ellen Gould White)\">Pr 318.1<\/span><\/p>\n<p id=\"1719\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1719\" data-refcode=\"Pr 318.2\"><span class=\"egw_content\" data-refcode=\"87.1719\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1726&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.2&quot;},{&quot;para_id&quot;:&quot;1765.2208&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.6&quot;},{&quot;para_id&quot;:&quot;2689.1701&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.2&quot;},{&quot;para_id&quot;:&quot;1871.1700&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.2&quot;}]\" data-refcode-old=\"Pr 318.2\">\u00ab Vous \u00eates complets en lui.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.60171#60171\" data-link=\"1965.60171\">Colossiens 2:10<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318.2 (Ellen Gould White)\">Pr 318.2<\/span><\/p>\n<p id=\"1720\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1720\" data-refcode=\"Pr 318.3\"><span class=\"egw_content\" data-refcode=\"87.1720\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2209&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.7&quot;},{&quot;para_id&quot;:&quot;190.1727&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.3&quot;},{&quot;para_id&quot;:&quot;2689.1702&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.3&quot;},{&quot;para_id&quot;:&quot;1871.1701&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.3&quot;}]\" data-refcode-old=\"Pr 318.3\">La pri\u00e8re et la foi sont \u00e9troitement li\u00e9es et doivent \u00eatre \u00e9tudi\u00e9es ensemble.\u00a0Dans la pri\u00e8re de la foi, il y a une science divine ;\u00a0c&rsquo;est une science que tous ceux qui veulent faire de leur travail une r\u00e9ussite doivent comprendre.\u00a0Christ dit : \u00ab Tout ce que vous d\u00e9sirez, quand vous priez, croyez que vous le recevez, et vous le recevrez.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.50340#50340\" data-link=\"1965.50340\">Marc 11:24<\/a>\u00a0.\u00a0Il explique clairement que notre demande doit \u00eatre conforme \u00e0 la volont\u00e9 de Dieu ;\u00a0nous devons demander les choses qu&rsquo;il a promises, et tout ce que nous recevons doit \u00eatre utilis\u00e9 pour faire sa volont\u00e9.\u00a0Les conditions r\u00e9unies, la promesse est sans \u00e9quivoque.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318.3 (Ellen Gould White)\">Pr 318.3<\/span><\/p>\n<p id=\"1721\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1721\" data-refcode=\"Pr 318.4\"><span class=\"egw_content\" data-refcode=\"87.1721\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1728&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.4&quot;},{&quot;para_id&quot;:&quot;1765.2210&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 375.8&quot;},{&quot;para_id&quot;:&quot;2689.1703&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.4&quot;},{&quot;para_id&quot;:&quot;1871.1702&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.4&quot;}]\" data-refcode-old=\"Pr 318.4\">Pour le pardon du p\u00e9ch\u00e9, pour le Saint-Esprit, pour un temp\u00e9rament semblable \u00e0 celui de Christ, pour la sagesse et la force de faire Son \u0153uvre, pour tout don qu&rsquo;Il a promis, nous pouvons demander ;\u00a0alors nous devons croire que nous recevons et rendre gr\u00e2ces \u00e0 Dieu que nous avons re\u00e7u.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318.4 (Ellen Gould White)\">Pr 318.4<\/span><\/p>\n<p id=\"1722\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1722\" data-refcode=\"Pr 318.5\"><span class=\"egw_content\" data-refcode=\"87.1722\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1729&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.5&quot;},{&quot;para_id&quot;:&quot;1765.2212&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 376.1&quot;},{&quot;para_id&quot;:&quot;2689.1704&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.5&quot;},{&quot;para_id&quot;:&quot;1871.1703&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.5&quot;}]\" data-refcode-old=\"Pr 318.5\">Nous n&rsquo;avons besoin de chercher aucune preuve ext\u00e9rieure de la b\u00e9n\u00e9diction.\u00a0Le don est dans la promesse, et nous pouvons accomplir notre travail en \u00e9tant assur\u00e9s que ce que Dieu a promis, Il est capable de l&rsquo;accomplir, et que le don, que nous poss\u00e9dons d\u00e9j\u00e0, sera r\u00e9alis\u00e9 lorsque nous en aurons le plus besoin.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318,5 (Ellen Gould White)\">Pr 318.5<\/span><\/p>\n<p id=\"1723\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1723\" data-refcode=\"Pr 318.6\"><span class=\"egw_content\" data-refcode=\"87.1723\" data-translate=\"[{&quot;para_id&quot;:&quot;2729.486&quot;,&quot;lang&quot;:&quot;de&quot;,&quot;refcode&quot;:&quot;DG 98.2&quot;},{&quot;para_id&quot;:&quot;1765.2213&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 376.2&quot;},{&quot;para_id&quot;:&quot;190.1730&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.6&quot;},{&quot;para_id&quot;:&quot;2689.1705&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.6&quot;},{&quot;para_id&quot;:&quot;1871.1703&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.5&quot;}]\" data-refcode-old=\"Pr 318.6\">Vivre ainsi par la parole de Dieu signifie l&rsquo;abandon \u00e0 Lui de toute la vie.\u00a0On ressentira un sentiment continuel de besoin et de d\u00e9pendance, un \u00e9lan du c\u0153ur vers Dieu.\u00a0La pri\u00e8re est une n\u00e9cessit\u00e9 ;\u00a0car c&rsquo;est la vie de l&rsquo;\u00e2me.\u00a0La pri\u00e8re familiale, la pri\u00e8re publique ont leur place ;\u00a0mais c&rsquo;est la communion secr\u00e8te avec Dieu qui soutient la vie de l&rsquo;\u00e2me.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318.6 (Ellen Gould White)\">Pr 318.6<\/span><\/p>\n<p id=\"1724\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1724\" data-refcode=\"Pr 318.7\"><span class=\"egw_content\" data-refcode=\"87.1724\" data-translate=\"[{&quot;para_id&quot;:&quot;2729.486&quot;,&quot;lang&quot;:&quot;de&quot;,&quot;refcode&quot;:&quot;DG 98.2&quot;},{&quot;para_id&quot;:&quot;190.1731&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.7&quot;},{&quot;para_id&quot;:&quot;1765.2214&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 376.3&quot;},{&quot;para_id&quot;:&quot;2689.1706&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 318.7&quot;},{&quot;para_id&quot;:&quot;1871.1704&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 318.6&quot;}]\" data-refcode-old=\"Pr 318.7\">C&rsquo;est sur la montagne avec Dieu que Mo\u00efse a vu le mod\u00e8le de ce merveilleux \u00e9difice qui devait \u00eatre le lieu de r\u00e9sidence de sa gloire.\u00a0C&rsquo;est sur la montagne avec Dieu \u2014 dans le lieu secret de la communion \u2014 que nous devons contempler son id\u00e9al glorieux pour l&rsquo;humanit\u00e9.\u00a0Ainsi, nous serons capables de fa\u00e7onner la construction de notre caract\u00e8re afin que nous puissions accomplir sa promesse : \u00ab J&rsquo;habiterai en eux et j&rsquo;y marcherai ;\u00a0et je serai leur Dieu, et ils seront mon peuple.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.58962#58962\" data-link=\"1965.58962\">2 Corinthiens 6:16<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 318.7 (Ellen Gould White)\">Pr 318.7<\/span><\/p>\n<p id=\"1726\" class=\"egw_content_wrapper standard-noindent\" data-para-id=\"87.1726\" data-refcode=\"Pr 319.1\"><span class=\"egw_content\" data-refcode=\"87.1726\" data-translate=\"[{&quot;para_id&quot;:&quot;2729.487&quot;,&quot;lang&quot;:&quot;de&quot;,&quot;refcode&quot;:&quot;DG 98.3&quot;},{&quot;para_id&quot;:&quot;190.1732&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 318.8&quot;},{&quot;para_id&quot;:&quot;1765.2215&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 376.4&quot;},{&quot;para_id&quot;:&quot;2689.1708&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 319.1&quot;},{&quot;para_id&quot;:&quot;1871.1706&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 319.1&quot;}]\" data-refcode-old=\"Pr 319.1\">C&rsquo;est au cours d&rsquo;heures de pri\u00e8re solitaire que J\u00e9sus, dans sa vie terrestre, a re\u00e7u sagesse et puissance.\u00a0Que les jeunes suivent son exemple en trouvant \u00e0 l&rsquo;aube et au cr\u00e9puscule une saison tranquille pour communier avec leur P\u00e8re c\u00e9leste.\u00a0Et tout au long de la journ\u00e9e, qu&rsquo;ils \u00e9l\u00e8vent leur c\u0153ur vers Dieu.\u00a0\u00c0 chaque pas de notre chemin, il dit : \u00ab Moi, l&rsquo;\u00c9ternel, ton Dieu, je tiendrai ta main droite,&#8230; N&rsquo;aie pas peur ;\u00a0Je vais t&rsquo;aider.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.37674#37674\" data-link=\"1965.37674\">Esa\u00efe 41:13<\/a>\u00a0.\u00a0Si nos enfants pouvaient apprendre ces le\u00e7ons au matin de leurs ann\u00e9es, quelle fra\u00eecheur et quelle puissance, quelle joie et quelle douceur seraient apport\u00e9es dans leur vie !\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 319.1 (Ellen Gould White)\">Pr 319.1<\/span><\/p>\n<p id=\"1727\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1727\" data-refcode=\"Pr 319.2\"><span class=\"egw_content\" data-refcode=\"87.1727\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1735&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 319.1&quot;},{&quot;para_id&quot;:&quot;1765.2216&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 376.5&quot;},{&quot;para_id&quot;:&quot;2689.1709&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 319.2&quot;},{&quot;para_id&quot;:&quot;1871.1707&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 319.2&quot;}]\" data-refcode-old=\"Pr 319.2\">Ce sont des le\u00e7ons que seul celui qui a appris lui-m\u00eame peut enseigner.\u00a0C&rsquo;est parce que tant de parents et d&rsquo;enseignants professent croire \u00e0 la parole de Dieu alors que leur vie nie sa puissance, que l&rsquo;enseignement de l&rsquo;\u00c9criture n&rsquo;a pas plus d&rsquo;effet sur les jeunes.\u00a0Parfois, les jeunes sont amen\u00e9s \u00e0 ressentir le pouvoir de la parole.\u00a0Ils voient la valeur de l&rsquo;amour de Christ.\u00a0Ils voient la beaut\u00e9 de son caract\u00e8re, les possibilit\u00e9s d&rsquo;une vie donn\u00e9e \u00e0 son service.\u00a0Mais en revanche, ils voient la vie de ceux qui professent v\u00e9n\u00e9rer les pr\u00e9ceptes de Dieu.\u00a0De combien sont vraies les paroles qui ont \u00e9t\u00e9 dites au proph\u00e8te Ez\u00e9chiel :\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 319.2 (Ellen Gould White)\">Pr 319.2<\/span><\/p>\n<p id=\"1728\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1728\" data-refcode=\"Pr 319.3\"><span class=\"egw_content\" data-refcode=\"87.1728\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1736&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 319.2&quot;},{&quot;para_id&quot;:&quot;1765.2219&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 377.1&quot;},{&quot;para_id&quot;:&quot;2689.1710&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 319.3&quot;},{&quot;para_id&quot;:&quot;1871.1707&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 319.2&quot;}]\" data-refcode-old=\"Pr 319.3\">Ton peuple \u00ab parle l&rsquo;un \u00e0 l&rsquo;autre, chacun \u00e0 son fr\u00e8re, disant : Venez, je vous prie, et \u00e9coutez quelle est la parole qui vient du Seigneur.\u00a0Et ils viennent \u00e0 toi comme le peuple vient, et ils s&rsquo;assoient devant toi comme mon peuple, et ils entendent tes paroles, mais ils ne les mettent pas en pratique : car avec leur bouche ils montrent beaucoup d&rsquo;amour, mais leur c\u0153ur va apr\u00e8s leur convoitise.\u00a0Et voici, tu es pour eux comme une tr\u00e8s belle chanson de quelqu&rsquo;un qui a une voix agr\u00e9able et sait bien jouer d&rsquo;un instrument : car ils entendent tes paroles, mais ils ne les font pas.\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.43484#43484\" data-link=\"1965.43484\">Ez\u00e9chiel 33:30-32<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 319.3 (Ellen Gould White)\">Pr 319.3<\/span><\/p>\n<p id=\"1729\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1729\" data-refcode=\"Pr 319.4\"><span class=\"egw_content\" data-refcode=\"87.1729\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2220&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 377.2&quot;},{&quot;para_id&quot;:&quot;190.1737&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 319.3&quot;},{&quot;para_id&quot;:&quot;2689.1711&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 319.4&quot;},{&quot;para_id&quot;:&quot;1871.1708&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 319.3&quot;}]\" data-refcode-old=\"Pr 319.4\">C&rsquo;est une chose de traiter la Bible comme un livre de bonne instruction morale, dont il faut tenir compte dans la mesure o\u00f9 cela est conforme \u00e0 l&rsquo;esprit du temps et \u00e0 notre position dans le monde ;\u00a0c&rsquo;en est une autre de la consid\u00e9rer telle qu&rsquo;elle est r\u00e9ellement : la parole du Dieu vivant, la parole qui est notre vie, la parole qui doit fa\u00e7onner nos actions, nos paroles et nos pens\u00e9es.\u00a0Consid\u00e9rer la parole de Dieu comme quelque chose de moins que cela, c&rsquo;est la rejeter.\u00a0Et ce rejet par ceux qui professent y croire, est au premier rang des causes de scepticisme et d&rsquo;infid\u00e9lit\u00e9 chez les jeunes.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 319.4 (Ellen Gould White)\">Pr 319.4<\/span><\/p>\n<p id=\"1731\" class=\"egw_content_wrapper standard-noindent\" data-para-id=\"87.1731\" data-refcode=\"Pr 320.1\"><span class=\"egw_content\" data-refcode=\"87.1731\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2221&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 377.3&quot;},{&quot;para_id&quot;:&quot;190.1739&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 320.1&quot;},{&quot;para_id&quot;:&quot;2689.1713&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 320.1&quot;},{&quot;para_id&quot;:&quot;1871.1710&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 320.1&quot;}]\" data-refcode-old=\"Pr 320.1\">Une intensit\u00e9 sans pr\u00e9c\u00e9dent prend possession du monde.\u00a0Dans l&rsquo;amusement, dans l&rsquo;argent, dans la lutte pour le pouvoir, dans la lutte m\u00eame pour l&rsquo;existence, il y a une force terrible qui absorbe le corps, l&rsquo;esprit et l&rsquo;\u00e2me.\u00a0Au milieu de cette course folle, Dieu parle.\u00a0Il nous demande de nous s\u00e9parer et de communier avec lui.\u00a0\u00ab\u00a0Tais-toi, et sache que je suis Dieu.\u00a0\u00bb\u00a0<a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.29794#29794\" data-link=\"1965.29794\">Psaume 46:10<\/a>\u00a0.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 320.1 (Ellen Gould White)\">Pr 320.1<\/span><\/p>\n<p id=\"1732\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1732\" data-refcode=\"Pr 320.2\"><span class=\"egw_content\" data-refcode=\"87.1732\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1740&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 320.2&quot;},{&quot;para_id&quot;:&quot;1765.2222&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 377.4&quot;},{&quot;para_id&quot;:&quot;2689.1714&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 320.2&quot;},{&quot;para_id&quot;:&quot;1871.1711&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 320.2&quot;}]\" data-refcode-old=\"Pr 320.2\">Beaucoup, m\u00eame dans leurs p\u00e9riodes de d\u00e9votion, ne re\u00e7oivent pas la b\u00e9n\u00e9diction de la vraie communion avec Dieu.\u00a0Ils sont trop press\u00e9s.\u00a0D&rsquo;un pas pr\u00e9cipit\u00e9, ils traversent le cercle de la pr\u00e9sence aimante du Christ, s&rsquo;arr\u00eatant peut-\u00eatre un instant dans l&rsquo;enceinte sacr\u00e9e, mais n&rsquo;attendant pas de conseil.\u00a0Ils n&rsquo;ont pas le temps de rester avec le divin Enseignant.\u00a0Avec leurs fardeaux, ils retournent \u00e0 leur travail.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 320.2 (Ellen Gould White)\">Pr 320.2<\/span><\/p>\n<p id=\"1733\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1733\" data-refcode=\"Pr 320.3\"><span class=\"egw_content\" data-refcode=\"87.1733\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2224&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 378.1&quot;},{&quot;para_id&quot;:&quot;190.1741&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 320.3&quot;},{&quot;para_id&quot;:&quot;2689.1715&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 320.3&quot;},{&quot;para_id&quot;:&quot;1871.1712&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 320.3&quot;}]\" data-refcode-old=\"Pr 320.3\">Ces travailleurs ne peuvent jamais atteindre le plus haut succ\u00e8s tant qu&rsquo;ils n&rsquo;ont pas appris le secret de la force.\u00a0Ils doivent se donner le temps de r\u00e9fl\u00e9chir, de prier, de s&rsquo;attendre \u00e0 ce que Dieu renouvelle leur puissance physique, mentale et spirituelle.\u00a0Ils ont besoin de l&rsquo;influence \u00e9difiante de son Esprit.\u00a0En recevant cela, ils seront vivifi\u00e9s par une nouvelle vie.\u00a0L&rsquo;ossature fatigu\u00e9e et le cerveau fatigu\u00e9 seront rafra\u00eechis, le c\u0153ur charg\u00e9 sera all\u00e9g\u00e9.\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 320.3 (Ellen Gould White)\">Pr 320.3<\/span><\/p>\n<p id=\"1734\" class=\"egw_content_wrapper standard-indented\" data-para-id=\"87.1734\" data-refcode=\"Pr 320.4\"><span class=\"egw_content\" data-refcode=\"87.1734\" data-translate=\"[{&quot;para_id&quot;:&quot;1765.2225&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 378.2&quot;},{&quot;para_id&quot;:&quot;190.1742&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 320.4&quot;},{&quot;para_id&quot;:&quot;2689.1716&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 320.4&quot;},{&quot;para_id&quot;:&quot;1871.1713&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 320.4&quot;}]\" data-refcode-old=\"Pr 320.4\">Pas une pause d&rsquo;un instant en sa pr\u00e9sence, mais un contact personnel avec le Christ, s&rsquo;asseoir en compagnie de lui, c&rsquo;est notre besoin.\u00a0Heureux sera-t-il pour les enfants de nos foyers et les \u00e9l\u00e8ves de nos \u00e9coles lorsque les parents et les enseignants apprendront dans leur propre vie la pr\u00e9cieuse exp\u00e9rience illustr\u00e9e dans ces paroles du Cantique des Cantiques :\u00a0<\/span><span class=\"egw_refcode\" title=\"Pri\u00e8re, p. 320.4 (Ellen Gould White)\">Pr 320.4<\/span><\/p>\n<p id=\"1735\" class=\"egw_content_wrapper poem-noindent\" data-para-id=\"87.1735\" data-refcode=\"Pr 320.5\"><span class=\"egw_content\" data-refcode=\"87.1735\" data-translate=\"[{&quot;para_id&quot;:&quot;190.1743&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or06 320.5&quot;},{&quot;para_id&quot;:&quot;1765.2226&quot;,&quot;lang&quot;:&quot;es&quot;,&quot;refcode&quot;:&quot;Or 378.3&quot;},{&quot;para_id&quot;:&quot;2689.1717&quot;,&quot;lang&quot;:&quot;ro&quot;,&quot;refcode&quot;:&quot;Rg 320.5&quot;},{&quot;para_id&quot;:&quot;1871.16091&quot;,&quot;lang&quot;:&quot;ru&quot;,&quot;refcode&quot;:&quot;\\u041c\\u043e\\u043b 320.5&quot;}]\" data-refcode-old=\"Pr 320.5\">\u00ab\u00a0Comme le pommier parmi les arbres de la for\u00eat,<br \/>\nAinsi est mon bien-aim\u00e9 parmi les fils.<br \/>\nJe me suis assis sous son ombre avec une grande joie,<br \/>\net son fruit \u00e9tait doux \u00e0 mon go\u00fbt.<br \/>\nIl m&rsquo;a amen\u00e9 \u00e0 la salle de banquet,<br \/>\nEt sa banni\u00e8re sur moi \u00e9tait l&rsquo;amour.\u00a0<span class=\"sameasprevious\"><a class=\"link egwlink egwlink_bible\" href=\"https:\/\/m.egwwritings.org\/en\/book\/1965.35812#35812\" data-link=\"1965.35812\">Cantiques 2:3, 4<\/a>\u00a0.\u00a0<\/span><\/span><\/p>\n<p data-para-id=\"87.1735\" data-refcode=\"Pr 320.5\"><strong>Source: Extrait des \u00e9crits de Ellen G. White sur la pri\u00e8re<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chapitre 32 \u2014 Foi et pri\u00e8re La foi, c&rsquo;est faire confiance \u00e0 Dieu, croire qu&rsquo;il nous aime et qu&rsquo;il sait mieux ce qui est pour notre bien.\u00a0Ainsi, au lieu de la n\u00f4tre, cela nous am\u00e8ne \u00e0 choisir sa voie.\u00a0Au lieu de notre ignorance, il accepte sa sagesse ;\u00a0\u00e0 la place de notre faiblesse, Sa force [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":3766,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[220,221,224,218],"tags":[843,274],"aioseo_notices":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/3764"}],"collection":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/comments?post=3764"}],"version-history":[{"count":2,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/3764\/revisions"}],"predecessor-version":[{"id":3767,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/3764\/revisions\/3767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media\/3766"}],"wp:attachment":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media?parent=3764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/categories?post=3764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/tags?post=3764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}