{"id":2828,"date":"2021-01-05T21:30:33","date_gmt":"2021-01-05T21:30:33","guid":{"rendered":"https:\/\/www.adventdesk.com\/home\/?p=2828"},"modified":"2021-01-05T21:31:47","modified_gmt":"2021-01-05T21:31:47","slug":"vaccins-covid-19-repondre-aux-preoccupations-offrir-des-conseils","status":"publish","type":"post","link":"https:\/\/www.adventdesk.com\/home\/vaccins-covid-19-repondre-aux-preoccupations-offrir-des-conseils\/","title":{"rendered":"Vaccins COVID-19: R\u00e9pondre Aux Pr\u00e9occupations, Offrir des Conseils"},"content":{"rendered":"<p><span class=\"byline-news\">Par: D\u00e9partement des minist\u00e8res de la sant\u00e9 de la Conf\u00e9rence g\u00e9n\u00e9rale, Institut de recherche biblique de la Conf\u00e9rence g\u00e9n\u00e9rale et \u00c9cole de pharmacie et \u00c9cole de sant\u00e9 publique de l&rsquo;Universit\u00e9 de Loma Linda<\/span><\/p>\n<p>Les Adventistes du jour m\u00eame consid\u00e8rent la venue du Christ comme le grand point culminant de l&rsquo;histoire et la fin de toute maladie, souffrance et mort. En m\u00eame temps, on nous a confi\u00e9 le message de sant\u00e9 adventiste incarn\u00e9 et d\u00e9velopp\u00e9 par les \u00e9crits d&rsquo;Ellen White, r\u00e9sumant une vie saine \u00e0 travers des comportements de vie sains pratiques et holistiques.<\/p>\n<p><!--more--><\/p>\n<p>Nous pr\u00e9conisons toutes ces pratiques pour maintenir un syst\u00e8me immunitaire sain, et dans la pand\u00e9mie, il en faut encore plus.\u00a0Ellen White n&rsquo;\u00e9tait pas seulement un vecteur inspir\u00e9 d&rsquo;informations sur la sant\u00e9 bien en avance sur son temps, mais elle a model\u00e9 la pr\u00e9vention pratique face \u00e0 la maladie mortelle \u00e0 son \u00e9poque, la variole, et a pris elle-m\u00eame la vaccination, tout comme ses proches.<sup>1<\/sup>\u00a0Aujourd&rsquo;hui, la variole a \u00e9t\u00e9 \u00e9radiqu\u00e9e \u00e0 l&rsquo;\u00e9chelle mondiale.<\/p>\n<p>Nous esp\u00e9rons que cet article r\u00e9pondra aux questions, apaisera les craintes et r\u00e9soudra certains des mythes et rumeurs r\u00e9pandus, apportant ainsi la paix dans le c\u0153ur de nos membres alors qu&rsquo;ils prennent des d\u00e9cisions en mati\u00e8re de sant\u00e9 guid\u00e9es par leurs fournisseurs de soins de sant\u00e9.<\/p>\n<p>Il y a des rumeurs et des th\u00e9ories du complot qui utilisent le vaccin COVID-19 comme interpr\u00e9tation et \/ ou r\u00e9alisation de la proph\u00e9tie.\u00a0Nous avons demand\u00e9 \u00e0 l&rsquo;Institut de recherche biblique de la Conf\u00e9rence g\u00e9n\u00e9rale des commentaires \u00e0 cet \u00e9gard, et la r\u00e9ponse est la suivante:<\/p>\n<p>\u00abLe bouleversement mondial caus\u00e9 par la pand\u00e9mie de COVID-19 a g\u00e9n\u00e9r\u00e9 des sp\u00e9culations consid\u00e9rables li\u00e9es aux \u00e9v\u00e9nements de la fin des temps et aux interpr\u00e9tations erron\u00e9es de la Bible.\u00a0Un point de vue r\u00e9cent, propag\u00e9 via les m\u00e9dias sociaux et certains sites Internet, a avanc\u00e9 la th\u00e9orie selon laquelle les vaccins \u00e0 venir produits pour lutter contre le COVID-19 appartiennent \u00e0 un processus de contr\u00f4le qui conduira \u00e0 l&rsquo;application de la marque de la b\u00eate.<\/p>\n<p>\u00abIl convient de noter, cependant, que les adventistes tiennent \u00e0 la conviction que la controverse de la fin des temps se concentrera sur la loi de Dieu, et en particulier sur le quatri\u00e8me commandement (\u00a0<a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/nkjv\/Rev%2014.12\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Rev 14.12\" data-version=\"nkjv\" data-purpose=\"bible-reference\">Ap 14:12<\/a>\u00a0).\u00a0De plus, le message du troisi\u00e8me ange mettra en garde contre la r\u00e9ception de la marque (\u00a0<a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/nkjv\/Rev%2014.9%E2%80%9311\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Rev 14.9\u201311\" data-version=\"nkjv\" data-purpose=\"bible-reference\">Ap 14: 9-11<\/a>\u00a0) et \u00e9clairera l&rsquo;humanit\u00e9 sur les probl\u00e8mes en jeu.<\/p>\n<p>\u00abPour cette raison, il devrait \u00eatre clair que les adventistes du septi\u00e8me jour comprennent que la\u00ab marque de la b\u00eate \u00bbn&rsquo;est pas une marque litt\u00e9rale mais un signe d&rsquo;all\u00e9geance qui identifie le porteur comme fid\u00e8le au pouvoir repr\u00e9sent\u00e9 par la b\u00eate.<\/p>\n<p>\u00abD&rsquo;un point de vue distinct, un autre point de vue sp\u00e9culatif soutient que les vaccins rendent ceux qui les prennent impurs parce que, soi-disant, des substances impures sont utilis\u00e9es pour les produire.\u00a0\u00c0 cet \u00e9gard, il convient de pr\u00e9ciser que les instructions bibliques permanentes interdisant la consommation d&rsquo;aliments et de sang impurs (\u00a0<a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/nkjv\/Lev%2011.1%E2%80%9320\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Lev 11.1\u201320\" data-version=\"nkjv\" data-purpose=\"bible-reference\">L\u00e9v 11: 1\u201320<\/a>\u00a0;\u00a0<a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/nkjv\/Lev%2017.11%E2%80%9312\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Lev 17.11\u201312\" data-version=\"nkjv\" data-purpose=\"bible-reference\">17: 11\u201312<\/a>\u00a0;\u00a0<a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/nkjv\/Acts%2015.20\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Acts 15.20\" data-version=\"nkjv\" data-purpose=\"bible-reference\">Actes 15:20<\/a>\u00a0) ne s&rsquo;appliquent pas aux vaccins pour la raison \u00e9vidente que les vaccins sont produits comme m\u00e9dicaments pour sauver des vies et non pour servir de nourriture.<\/p>\n<p>\u00abDe telles sp\u00e9culations jettent le discr\u00e9dit sur la Parole de Dieu et s\u00e8ment la confusion parmi les croyants sinc\u00e8res mais moins inform\u00e9s.\u00a0Utiliser l&rsquo;introduction d&rsquo;un vaccin pour susciter un sc\u00e9nario eschatologique aux proportions spirituelles et cosmiques, ou pour s&rsquo;y opposer sur la base d&rsquo;une interpr\u00e9tation erron\u00e9e des \u00c9critures, ne fait que distraire les croyants sinc\u00e8res des v\u00e9ritables probl\u00e8mes proph\u00e9tiques et de l&rsquo;engagement de l&rsquo;\u00c9glise adventiste \u00e0 proclamer l&rsquo;\u00c9vangile. .<\/p>\n<p>\u00abEsp\u00e9rons qu&rsquo;un vaccin efficace aidera \u00e0 mettre un terme \u00e0 la pand\u00e9mie actuelle.\u00a0Cela prot\u00e9gera la vie de ceux qui ont encore besoin de conna\u00eetre l&rsquo;\u00c9vangile, ainsi que de ceux qui ont d\u00e9j\u00e0 accept\u00e9 l&rsquo;\u00c9vangile et sont ainsi charg\u00e9s de la proclamation de l&rsquo;amour infini de Dieu \u00e0 un monde souffrant (\u00a0<a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/nkjv\/John%203.16\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"John 3.16\" data-version=\"nkjv\" data-purpose=\"bible-reference\">Jean 3:16<\/a>\u00a0).<sup>2<\/sup><\/p>\n<p>Adventist Health Ministries est fermement bas\u00e9 sur la Bible, l&rsquo;instruction de l&rsquo;Esprit de Proph\u00e9tie par Ellen White, et est en accord avec la science de la sant\u00e9 \u00e9valu\u00e9e par des pairs et fond\u00e9e sur des preuves.\u00a0Nous nous appuyons sur ces bases pour formuler des approches et des conseils en mati\u00e8re de sant\u00e9.\u00a0Avec des millions d&rsquo;infect\u00e9s et de nombreux morts, et des infections mondiales en augmentation, un certain nombre de vaccins ont \u00e9t\u00e9 d\u00e9velopp\u00e9s en un temps record.\u00a0Les gens se posent de nombreuses questions concernant le vaccin COVID-19.<\/p>\n<p>En tant qu&rsquo;\u00e9glise, bien que nous soutenions les recommandations de sant\u00e9 publique fond\u00e9es sur des donn\u00e9es probantes, nous veillons \u00e9galement \u00e0 ne pas faire de d\u00e9clarations qui pourraient \u00eatre interpr\u00e9t\u00e9es comme rempla\u00e7ant les directives nationales et internationales de sant\u00e9 publique.\u00a0Pour cette raison, il est important que nos commentaires soient compris dans le cadre de notre\u00a0<a href=\"https:\/\/www.adventist.org\/articles\/immunization\/\" target=\"_blank\" rel=\"noopener noreferrer\">position officielle de l&rsquo;\u00c9glise sur la vaccination<\/a>\u00a0:<\/p>\n<p>\u00abL&rsquo;\u00c9glise adventiste du septi\u00e8me jour met fortement l&rsquo;accent sur la sant\u00e9 et le bien-\u00eatre.\u00a0L&rsquo;accent sur la sant\u00e9 adventiste est bas\u00e9 sur la r\u00e9v\u00e9lation biblique, l&rsquo;\u00e9criture inspir\u00e9e d&rsquo;EG White (co-fondateur de l&rsquo;\u00c9glise) et sur la litt\u00e9rature scientifique \u00e9valu\u00e9e par des pairs.\u00a0En tant que tel, nous encourageons l&rsquo;immunisation \/ vaccination responsable, et n&rsquo;avons aucune raison religieuse ou religieuse de ne pas encourager nos adh\u00e9rents \u00e0 participer de mani\u00e8re responsable aux programmes de vaccination protectrice et pr\u00e9ventive.\u00a0Nous appr\u00e9cions la sant\u00e9 et la s\u00e9curit\u00e9 de la population, ce qui inclut le maintien de \u00abl&rsquo;immunit\u00e9 collective\u00bb.<\/p>\n<p>\u00abNous ne sommes pas la conscience du membre individuel de l&rsquo;\u00e9glise et reconnaissons les choix individuels.\u00a0Ceux-ci sont exerc\u00e9s par l&rsquo;individu.\u00a0Le choix de ne pas \u00eatre immunis\u00e9 n&rsquo;est pas et ne doit pas \u00eatre consid\u00e9r\u00e9 comme le dogme ni la doctrine de l&rsquo;\u00c9glise adventiste du septi\u00e8me jour.<\/p>\n<p>Des efforts ont \u00e9t\u00e9 faits pour \u00e9tablir une approche fiable du traitement du COVID-19 fond\u00e9e sur des preuves.\u00a0De plus, et en un temps record, des vaccins ont \u00e9t\u00e9 produits et sont maintenant utilis\u00e9s pour aider \u00e0 ma\u00eetriser la pand\u00e9mie.\u00a0Cependant, les gens ont des inqui\u00e9tudes et des questions concernant les vaccins COVID-19.<\/p>\n<p>L&rsquo;autorisation d&rsquo;utilisation d&rsquo;urgence (EUA) du vaccin Pfizer \/ BioNtech a \u00e9t\u00e9 accord\u00e9e le 2 d\u00e9cembre 2020 au Royaume-Uni et le 9 d\u00e9cembre au Canada.\u00a0Aux \u00c9tats-Unis, le vaccin Pfizer a \u00e9t\u00e9 examin\u00e9 par la Food and Drug Administration (FDA) des \u00c9tats-Unis et autoris\u00e9 provisoirement le 11 d\u00e9cembre. Le vaccin Moderna suivra.<\/p>\n<p>En conversation avec la Loma Linda University School of Public Health (LLUSPH), Michael Hogue, doyen de la Loma Linda School of Pharmacy, qui si\u00e8ge au comit\u00e9 consultatif des Centers for Disease Control (CDC) des \u00c9tats-Unis sur le groupe de travail sur les pratiques d&rsquo;immunisation sur les vaccins COVID-19 et sur le groupe de travail sur le vaccin COVID-19 du comt\u00e9 de San Bernardino en Californie, a partag\u00e9 les informations suivantes concernant les questions fr\u00e9quemment pos\u00e9es sur les vaccins Pfizer \/ BioNtech et Moderna.\u00a0Ses id\u00e9es et explications sur les questions courantes figurent ci-dessous.<\/p>\n<p><strong>Questions et faits sur le vaccin<\/strong><\/p>\n<p><strong>Question: Le vaccin \u00e0 ARNm (acide ribonucl\u00e9ique messager) modifie-t-il votre ADN?<\/strong><\/p>\n<p><strong>FAIT:<\/strong>\u00a0Les deux vaccins r\u00e9f\u00e9renc\u00e9s sont bas\u00e9s sur l&rsquo;ARNm, ce qui est une premi\u00e8re pour les vaccins, mais la technologie est utilis\u00e9e dans les traitements m\u00e9dicaux depuis 15 ans.\u00a0Le vaccin p\u00e9n\u00e8tre dans le cytoplasme d&rsquo;une cellule (le fluide \u00e0 l&rsquo;int\u00e9rieur de la cellule), o\u00f9 il stimule la production d&rsquo;anticorps pour combattre la prot\u00e9ine de pointe du SRAS-CoV-2.\u00a0Comme il n&rsquo;entre pas dans le noyau de la cellule h\u00f4te, il ne modifie pas l&rsquo;ADN ou la structure \/ fonction g\u00e9n\u00e9tique.<\/p>\n<p><strong>Question: Peut-il \u00eatre s\u00fbr et efficace, car il a \u00e9t\u00e9 d\u00e9velopp\u00e9 si rapidement?<\/strong><\/p>\n<p><strong>FAIT:<\/strong>\u00a0En raison de la technologie actuelle, le virus SRAS-CoV-2 a \u00e9t\u00e9 s\u00e9quenc\u00e9 quelques jours apr\u00e8s son identification, et les travaux sur un vaccin ont commenc\u00e9 imm\u00e9diatement.\u00a0La taille de l&rsquo;\u00e9chantillon pour la grande \u00e9tude est de 40 000 personnes (la taille moyenne de l&rsquo;\u00e9chantillon d&rsquo;\u00e9tude de vaccin de la FDA n&rsquo;est g\u00e9n\u00e9ralement que de 27 000).\u00a0Nous sommes \u00e0 deux mois d&rsquo;une \u00e9tude de deux ans.\u00a0Les donn\u00e9es sont surveill\u00e9es attentivement.<\/p>\n<p>La premi\u00e8re dose a montr\u00e9 une protection de la r\u00e9ponse immunitaire de 50 pour cent.\u00a0La deuxi\u00e8me dose a atteint 95% de protection!\u00a0(Seul le vaccin contre l&rsquo;h\u00e9patite A est plus \u00e9lev\u00e9, avec une protection d&rsquo;environ 100%.) L&rsquo;\u00e9tude \u00e9tait bien con\u00e7ue et repr\u00e9sentait de tr\u00e8s pr\u00e8s la d\u00e9mographie am\u00e9ricaine, \u00e0 l&rsquo;exception des Am\u00e9rindiens (et l&rsquo;\u00e9tude en cours s&rsquo;efforce d&rsquo;y rem\u00e9dier).\u00a0L&rsquo;efficacit\u00e9 et les effets secondaires \u00e9taient similaires dans tous les groupes ethniques.<\/p>\n<p><strong>Question: Les ingr\u00e9dients et les conservateurs du vaccin sont-ils dangereux?<\/strong><\/p>\n<p><strong>FAIT:<\/strong>\u00a0Il n&rsquo;y a pas de conservateurs dans ces deux vaccins COVID-19, c&rsquo;est pourquoi ils n\u00e9cessitent des installations de cong\u00e9lation \/ cong\u00e9lation pour le stockage et le transport.\u00a0Le vaccin est soigneusement purifi\u00e9.<\/p>\n<p><strong>Question: Quels sont les effets secondaires?\u00a0<\/strong><\/p>\n<p><strong>FAIT:<\/strong>\u00a0Jusqu&rsquo;\u00e0 pr\u00e9sent, 10% des sujets ont signal\u00e9 de la fi\u00e8vre le deuxi\u00e8me jour, et en 24 heures, 50 \u00e0 60% ont d\u00e9clar\u00e9 se sentir \u00abendoloris\u00bb.\u00a0Jusqu&rsquo;\u00e0 pr\u00e9sent, il y a eu tr\u00e8s peu d&rsquo;effets secondaires graves avec le vaccin Pfizer \/ BioNtech, y compris trois cas de r\u00e9actions allergiques significatives (anormalement faibles; probablement en raison de la non-utilisation de conservateurs).<\/p>\n<p>Le Dr Hogue a ajout\u00e9 que si une personne a d\u00e9j\u00e0 test\u00e9 COVID-19 positif dans le pass\u00e9, cette personne peut toujours se faire vacciner;\u00a0cela augmentera simplement les niveaux d&rsquo;anticorps de la personne.\u00a0Il a \u00e9galement soulign\u00e9 que la prise du vaccin aux \u00c9tats-Unis est volontaire et non obligatoire.<\/p>\n<p>L&rsquo;efficacit\u00e9 des vaccins Pfizer \/ BioNtech et Moderna est similaire, mais ils ne sont pas interchangeables (si une personne commence par un, la deuxi\u00e8me dose doit \u00eatre de la m\u00eame marque).\u00a0Pour le vaccin Pfizer, il y a un intervalle de 21 jours entre les deux doses;\u00a0il est rapport\u00e9 que pour le vaccin Moderna, l&rsquo;intervalle sera de 28 jours entre les doses.\u00a0Le vaccin n&rsquo;est pas autoris\u00e9 pendant la grossesse ou chez les personnes de moins de 16 ans.<\/p>\n<p><strong>Conclusion<\/strong><\/p>\n<p>La vaccination, avec l&rsquo;assainissement et l&rsquo;eau potable, a \u00e9t\u00e9 fondamentale pour l&rsquo;am\u00e9lioration de la long\u00e9vit\u00e9 observ\u00e9e dans le monde entier o\u00f9 ces interventions ont \u00e9t\u00e9 appliqu\u00e9es.\u00a0Les vaccins ont longtemps \u00e9t\u00e9 utilis\u00e9s par les membres d&rsquo;\u00e9glises adventistes \u00e0 travers le monde.\u00a0En plus de bonnes pratiques de sant\u00e9, ils ont fourni une protection contre de nombreuses infections et \u00e9vit\u00e9 la maladie et la mort.<\/p>\n<p>Alors que nous sommes t\u00e9moins de l&rsquo;ampleur mondiale de la pand\u00e9mie, des d\u00e9c\u00e8s, des incapacit\u00e9s et des effets \u00e0 long terme du COVID-19 qui \u00e9mergent dans tous les groupes d&rsquo;\u00e2ge, nous encourageons nos membres \u00e0 envisager une vaccination responsable et la promotion et la facilitation du d\u00e9veloppement de ce est commun\u00e9ment appel\u00e9e\u00a0<em>immunit\u00e9<\/em>\u00a0collective (immunit\u00e9 communautaire pr\u00e9existante d&rsquo;environ 80 pour cent des individus \u00e0 la suite d&rsquo;une infection et \/ ou d&rsquo;une vaccination ant\u00e9rieures).<\/p>\n<p>Nous r\u00e9it\u00e9rons:\u00a0<strong>LA D\u00c9CISION D&rsquo;\u00caTRE IMMUNIS\u00c9 OU NON EST LE CHOIX DE CHAQUE INDIVIDU ET DOIT \u00caTRE PRISE EN CONSULTATION AVEC SON PRESTATAIRE DE SOINS DE SANT\u00c9.\u00a0LA RECHERCHE PERSONNELLE SUR LE SUJET EST IMPORTANTE.\u00a0NOUS NOUS FIXONS ULTIMATEMENT SUR LE SUIVI DES PRATIQUES DE SANT\u00c9 BIBLIQUE ET L&rsquo;ESPRIT DE PROPH\u00c9TIE, ET SUR LE SUIVI DE LA DIRECTION DE DIEU DANS NOTRE VIE, QUI NOUS APPORTERA PAIX ET ASSURANCE DANS NOTRE PRISE DE D\u00c9CISION.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>____________________________<\/p>\n<p>1. Concernant la vaccination contre la variole, DE Robinson, une des secr\u00e9taires d&rsquo;Ellen White, \u00e0 la date du 12 juin 1931, a \u00e9crit ce qui suit concernant l&rsquo;attitude de Mme White \u00e0 l&rsquo;\u00e9gard de la vaccination:<\/p>\n<p>\u00abVous demandez des informations pr\u00e9cises et concises sur ce que S\u0153ur White a \u00e9crit sur la vaccination et le s\u00e9rum.<\/p>\n<p><span class=\"goog-text-highlight\">\u00abOn peut r\u00e9pondre tr\u00e8s bri\u00e8vement \u00e0 cette question, car pour autant que nous ayons des informations, elle ne les a pas mentionn\u00e9es dans aucun de ses \u00e9crits.<\/span><\/p>\n<p>\u00abVous serez cependant int\u00e9ress\u00e9 de savoir qu&rsquo;\u00e0 un moment o\u00f9 il y avait une \u00e9pid\u00e9mie de variole dans les environs, elle-m\u00eame a \u00e9t\u00e9 vaccin\u00e9e et a exhort\u00e9 ses assistants, ceux qui lui \u00e9taient li\u00e9s, \u00e0 se faire vacciner.\u00a0En franchissant cette \u00e9tape, S\u0153ur White a reconnu le fait qu&rsquo;il a \u00e9t\u00e9 prouv\u00e9 que la vaccination immunise la personne contre la variole ou en att\u00e9nue consid\u00e9rablement les effets si elle en souffre.\u00a0Elle a \u00e9galement reconnu le danger qu&rsquo;ils exposent les autres s&rsquo;ils ne prennent pas cette pr\u00e9caution.\u00a0[Sign\u00e9] DE Robinson \u00bb(\u00a0<em>Selected Messages<\/em>\u00a0, bk. 2, p. 303).<\/p>\n<p>2. Institut de recherche biblique de la Conf\u00e9rence g\u00e9n\u00e9rale des adventistes du septi\u00e8me jour, d\u00e9cembre 2020.<\/p>\n<p><strong>Source: Adventist Review<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par: D\u00e9partement des minist\u00e8res de la sant\u00e9 de la Conf\u00e9rence g\u00e9n\u00e9rale, Institut de recherche biblique de la Conf\u00e9rence g\u00e9n\u00e9rale et \u00c9cole de pharmacie et \u00c9cole de sant\u00e9 publique de l&rsquo;Universit\u00e9 de Loma Linda Les Adventistes du jour m\u00eame consid\u00e8rent la venue du Christ comme le grand point culminant de l&rsquo;histoire et la fin de toute [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2830,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[220,218],"tags":[1181,1180],"aioseo_notices":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2828"}],"collection":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/comments?post=2828"}],"version-history":[{"count":2,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2828\/revisions"}],"predecessor-version":[{"id":2831,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2828\/revisions\/2831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media\/2830"}],"wp:attachment":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media?parent=2828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/categories?post=2828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/tags?post=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}