{"id":2752,"date":"2020-11-17T21:40:56","date_gmt":"2020-11-17T21:40:56","guid":{"rendered":"https:\/\/www.adventdesk.com\/home\/?p=2752"},"modified":"2020-11-17T21:40:56","modified_gmt":"2020-11-17T21:40:56","slug":"les-contributions-dellen-g-white-a-leglise-adventiste-du-septieme-jour","status":"publish","type":"post","link":"https:\/\/www.adventdesk.com\/home\/les-contributions-dellen-g-white-a-leglise-adventiste-du-septieme-jour\/","title":{"rendered":"Les contributions d&rsquo;Ellen G. White \u00e0 l&rsquo;\u00c9glise Adventiste du Septi\u00e8me jour"},"content":{"rendered":"<p>Par Gerhard Pfandl, PhD.<\/p>\n<p>Quelques mots sur la mani\u00e8re dont les ann\u00e9es de formation de l&rsquo;\u00c9glise adventiste du septi\u00e8me jour ont \u00e9t\u00e9 influenc\u00e9es par l&rsquo;une de ses fondatrices, Ellen G. White.<\/p>\n<p><span>Les contributions de Ellen G. White \u00e0 l&rsquo;\u00c9glise adventiste du septi\u00e8me jour ont \u00e9t\u00e9 inestimables dans de nombreux domaines et tout au long de l&rsquo;histoire de l&rsquo;\u00e9glise, mais en particulier pendant les premi\u00e8res ann\u00e9es. Les contributions suivantes sont parmi les plus importantes.<\/span><\/p>\n<p><!--more--><\/p>\n<h2><span><strong>ORGANISATION DE L&rsquo;\u00a0<\/strong><strong>\u00c9GLISE\u00a0<\/strong><\/span><\/h2>\n<p><span>Pendant les 20 premi\u00e8res ann\u00e9es de notre \u00e9glise, il n&rsquo;y avait pas d&rsquo;organisation d&rsquo;\u00e9glise parce que les mill\u00e9rites et les premiers adventistes \u00e9taient contre toute organisation d&rsquo;\u00e9glise.\u00a0Ils consid\u00e9raient toutes les \u00e9glises organis\u00e9es comme appartenant \u00e0 Babylone.\u00a0Par cons\u00e9quent, il n&rsquo;y avait pas de minist\u00e8re r\u00e9mun\u00e9r\u00e9;\u00a0nos pionniers ont occup\u00e9 divers emplois pour gagner leur vie.\u00a0James White, par exemple, tondait l&rsquo;herbe, coupait du bois et travaillait \u00e0 la construction d&rsquo;un chemin de fer pour subvenir aux besoins de sa famille.\u00a0De plus, n&rsquo;importe qui peut pr\u00eacher s&rsquo;il se sent appel\u00e9;\u00a0par cons\u00e9quent, les h\u00e9r\u00e9sies ont prosp\u00e9r\u00e9.<\/span><\/p>\n<p><span>De plus, les premiers b\u00e2timents \u00e9taient entre des mains priv\u00e9es.\u00a0La question de la propri\u00e9t\u00e9 l\u00e9gale a finalement propuls\u00e9 l&rsquo;\u00e9glise dans une organisation formelle.\u00a0En 1853, James White a exhort\u00e9 les croyants \u00e0 s&rsquo;organiser, mais la r\u00e9sistance \u00e0 l&rsquo;organisation \u00e9tait forte.\u00a0Un an plus tard, Ellen White a \u00e9crit: \u00abLe Seigneur a montr\u00e9 que l&rsquo;ordre de l&rsquo;\u00c9vangile \u00e9tait trop craint et n\u00e9glig\u00e9.\u00a0La formalit\u00e9 doit \u00eatre \u00e9vit\u00e9e;\u00a0mais, ce faisant, l&rsquo;ordre ne doit pas \u00eatre n\u00e9glig\u00e9.\u00a0Il y a de l&rsquo;ordre dans le ciel.\u00a0Il y avait de l&rsquo;ordre dans l&rsquo;\u00e9glise quand Christ \u00e9tait sur la terre.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00ab.\u00a0.\u00a0.\u00a0Le danger de ceux qui voyagent que Dieu n&rsquo;a pas appel\u00e9s, m&rsquo;a \u00e9t\u00e9 montr\u00e9.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abJ&rsquo;ai vu que cette porte par laquelle l&rsquo;ennemi entre pour troubler et troubler le troupeau peut \u00eatre ferm\u00e9e.\u00a0J&rsquo;ai demand\u00e9 \u00e0 l&rsquo;ange comment il pouvait \u00eatre ferm\u00e9.\u00a0Il a dit: \u00abL&rsquo;\u00c9glise doit fuir vers la Parole de Dieu et s&rsquo;\u00e9tablir sur l&rsquo;ordre de l&rsquo;\u00c9vangile, qui a \u00e9t\u00e9 n\u00e9glig\u00e9 et n\u00e9glig\u00e9.\u00a0\u00ab\u00a01<\/span><\/p>\n<p><span>Six autres ann\u00e9es se sont \u00e9coul\u00e9es avant que les premi\u00e8res \u00e9glises ne soient organis\u00e9es en 1860 dans le Michigan.\u00a0Un an plus tard, la Conf\u00e9rence du Michigan \u00e9tait organis\u00e9e et, en 1863, la Conf\u00e9rence G\u00e9n\u00e9rale. \u00c0 cette \u00e9poque, l&rsquo;effectif total se composait d&rsquo;environ 3 500 croyants baptis\u00e9s.\u00a0Aujourd&rsquo;hui, l&rsquo;\u00e9glise compte plus de 22 millions de membres dans plus de 75 000 \u00e9glises.<\/span><\/p>\n<h2><strong><span>PUBLICATIONS<\/span><\/strong><\/h2>\n<p><span>En 1848, Ellen White eut une vision dans la maison d&rsquo;Otis Nichol \u00e0 Dorchester, Massachusetts.\u00a0Quand elle est sortie de la vision, elle a dit \u00e0 son mari, James: \u00abJ&rsquo;ai un message pour vous.\u00a0Vous devez commencer \u00e0 imprimer un peu de papier et l&rsquo;envoyer aux gens.\u00a0Que ce soit petit au d\u00e9but;\u00a0mais comme les gens liront, ils vous enverront des moyens pour imprimer, et ce sera un succ\u00e8s d\u00e8s le d\u00e9but.\u00a0Depuis ce petit d\u00e9but, il m&rsquo;est apparu comme des flots de lumi\u00e8re qui parcouraient le monde.\u00a0\u00ab\u00a02<\/span><\/p>\n<p><span>\u00ab&rsquo;Des flots de lumi\u00e8re.\u00a0.\u00a0.\u00a0clair dans le monde \u00bb\u00bb!\u00a0Comment cela pourrait-il \u00eatre?\u00a0J\u00e9sus venait bient\u00f4t.\u00a0Leur nombre \u00e9tait peu \u00e9lev\u00e9.\u00a0Il n&rsquo;y avait pas de membres riches et pas de grands savants parmi eux.\u00a0Le monde \u00e9tait incr\u00e9dule.\u00a0Et pourtant, voici une jeune femme qui a pr\u00e9dit qu&rsquo;un travail d&rsquo;\u00e9dition \u00e0 commencer par son mari sans le sou grandirait jusqu&rsquo;\u00e0 ce qu&rsquo;il englobe le globe.\u00a0Plus de six mois se sont \u00e9coul\u00e9s avant que James White ne puisse faire le moindre d\u00e9but;\u00a0il a organis\u00e9 l&rsquo;impression de mille exemplaires d&rsquo;un papier de huit pages sur de l&rsquo;argent emprunt\u00e9.\u00a0Aujourd&rsquo;hui, l&rsquo;\u00e9glise compte 63 maisons d&rsquo;\u00e9dition qui produisent des livres et des magazines dans plus de 360 \u200b\u200blangues.<\/span><\/p>\n<h2><strong><span>SANT\u00c9 ET TRAVAIL M\u00c9DICAL<\/span><\/strong><\/h2>\n<p><span>Nos pionniers, au cours des 20 premi\u00e8res ann\u00e9es de notre histoire, \u00e9taient tout sauf des r\u00e9formateurs de la sant\u00e9, \u00e0 l&rsquo;exception de Joseph Bates.\u00a0Pendant les conf\u00e9rences du sabbat de 1848, ils se sont assis ensemble pour fumer la pipe.\u00a0Cette ann\u00e9e-l\u00e0, on a montr\u00e9 \u00e0 Ellen White que le tabac, le th\u00e9 et le caf\u00e9 sont nocifs, mais il a fallu de nombreuses ann\u00e9es pour convaincre les membres de se passer de ces substances nocives.<\/span><\/p>\n<p><span>Puis, le 6 juin 1863, Ellen White re\u00e7ut une vision de 45 minutes dans laquelle la n\u00e9cessit\u00e9 d&rsquo;une r\u00e9forme de la sant\u00e9 \u00e9tait montr\u00e9e: \u00abJ&rsquo;ai vu que c&rsquo;\u00e9tait un devoir sacr\u00e9 de s&rsquo;occuper de notre sant\u00e9 et d&rsquo;\u00e9veiller les autres \u00e0 leur devoir.\u00a0.\u00a0.\u00a0.\u00a0Nous avons le devoir de parler, de nous opposer aux intemp\u00e9rances de toutes sortes, \u00e0 l&rsquo;intemp\u00e9rance de travailler, de manger, de boire.\u00a0.\u00a0. &#8211; et ensuite les orienter vers le grand m\u00e9dicament de Dieu, l&rsquo;eau, l&rsquo;eau douce pure, pour les maladies, pour la sant\u00e9, pour la propret\u00e9.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abJ&rsquo;ai vu que nous ne devrions pas garder le silence sur le sujet de la sant\u00e9, mais que nous devrions r\u00e9veiller les esprits sur le sujet.\u00bb 3<\/span><\/p>\n<p><span>Deux ans plus tard, le 25 d\u00e9cembre 1865, Ellen White eut une vision \u00e0 Rochester, New York, dans laquelle on lui montra que l&rsquo;\u00e9glise \u00abdevrait fournir un foyer aux afflig\u00e9s et \u00e0 ceux qui souhaitent apprendre \u00e0 prendre soin de leur corps. afin de pr\u00e9venir la maladie.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abNotre peuple doit avoir sa propre institution, sous son propre contr\u00f4le, au profit des malades et des souffrants parmi nous qui souhaitent avoir la sant\u00e9 et la force pour glorifier Dieu dans leur corps et leur esprit, qui sont les siens.\u00bb 4 En cons\u00e9quence, un an plus tard, en septembre 1866, le Western Health Reform Institute de Battle Creek a \u00e9t\u00e9 ouvert.\u00a0Aujourd&rsquo;hui, l&rsquo;\u00e9glise g\u00e8re 175 h\u00f4pitaux et sanatoriums et 270 cliniques et dispensaires \u00e0 travers le monde.<\/span><\/p>\n<h2><strong><span>\u00c9DUCATION<\/span><\/strong><\/h2>\n<p><span>En 1872, Ellen White a re\u00e7u une vision sur les principes appropri\u00e9s de l&rsquo;\u00e9ducation.\u00a0Peu de temps apr\u00e8s, elle \u00e9crivit 30 pages sur ce qu&rsquo;on lui avait dit.\u00a0\u00abNous avons besoin d&rsquo;une \u00e9cole o\u00f9 ceux qui viennent d&rsquo;entrer dans le minist\u00e8re peuvent apprendre au moins les branches communes de l&rsquo;\u00e9ducation, et o\u00f9 ils peuvent \u00e9galement apprendre plus parfaitement les v\u00e9rit\u00e9s de la parole de Dieu pour cette \u00e9poque.\u00bb 5<\/span><\/p>\n<p><span>Le 24 ao\u00fbt 1874, le Battle Creek College a ouvert ses portes.\u00a0Aujourd&rsquo;hui, nous avons plus de 7 000 \u00e9coles primaires et secondaires et plus de 100 coll\u00e8ges et universit\u00e9s.\u00a0Les adventistes du septi\u00e8me jour ont le plus grand syst\u00e8me scolaire protestant au monde.\u00a0Pourquoi?\u00a0Parce que nos pionniers ont pris au s\u00e9rieux ce que Dieu leur a dit \u00e0 travers le proph\u00e8te de l&rsquo;\u00e9glise du reste.<\/span><\/p>\n<h2><strong>MISSION<\/strong><\/h2>\n<p><span>Au cours des premi\u00e8res d\u00e9cennies de notre histoire, ils croyaient que l&rsquo;\u00c9glise accomplissait le commandement de Dieu d&rsquo;enseigner \u00e0 toutes les nations en pr\u00eachant aux immigrants d&rsquo;Am\u00e9rique du Nord.\u00a0Uriah Smith a \u00e9crit en 1859: \u00abNous n&rsquo;avons aucune information selon laquelle le Troisi\u00e8me Message [de l&rsquo;Ange] est actuellement proclam\u00e9 dans un pays autre que le n\u00f4tre.\u00a0.\u00a0.\u00a0.\u00a0Notre propre pays est compos\u00e9 de personnes de presque toutes les nations. \u00bb6 Pour atteindre ces nations en Am\u00e9rique, des publications ont \u00e9t\u00e9 r\u00e9dig\u00e9es dans de nombreuses langues diff\u00e9rentes.<\/span><\/p>\n<p><span>Lorsqu&rsquo;en 1864 MB Czechowski se porta volontaire pour aller comme missionnaire en Europe, sa demande fut rejet\u00e9e.\u00a0Il est all\u00e9 voir les adventistes du premier jour, et ils l&rsquo;ont envoy\u00e9 en Europe, o\u00f9 il a pr\u00each\u00e9 les messages des trois anges et a \u00e9tabli des soci\u00e9t\u00e9s adventistes du septi\u00e8me jour.\u00a0Dans l&rsquo;intervalle, Ellen White a \u00e9duqu\u00e9 l&rsquo;\u00e9glise sur sa responsabilit\u00e9 mondiale.\u00a0En 1871, elle \u00e9crivait: \u00abBeaucoup peut \u00eatre fait par l&rsquo;interm\u00e9diaire de la presse, mais encore plus peut \u00eatre accompli si l&rsquo;influence des travaux des pr\u00e9dicateurs vivants accompagne nos publications.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abLorsque les \u00e9glises verront de jeunes hommes faire preuve de z\u00e8le pour se qualifier pour \u00e9tendre leurs travaux \u00e0 des villes, villages et villes qui n&rsquo;ont jamais \u00e9t\u00e9 \u00e9veill\u00e9s \u00e0 la v\u00e9rit\u00e9, et des missionnaires se porter volontaires pour aller dans d&rsquo;autres nations pour leur porter la v\u00e9rit\u00e9, les \u00e9glises \u00eatre encourag\u00e9s et renforc\u00e9s. \u00bb7<\/span><\/p>\n<p><span>Et, en 1874, elle avait un r\u00eave impressionnant de transmettre le message du troisi\u00e8me ange au monde.\u00a0Dans le r\u00eave, on lui a dit: \u00abVous avez des id\u00e9es trop limit\u00e9es du travail pour cette fois.\u00a0Vous essayez de planifier le travail de mani\u00e8re \u00e0 pouvoir le prendre dans vos bras.\u00a0Vous devez avoir une vision plus large.\u00a0Votre lumi\u00e8re ne doit pas \u00eatre plac\u00e9e sous un boisseau ou sous un lit, mais sur un chandelier, afin qu&rsquo;elle puisse \u00e9clairer tout ce qui se trouve dans la maison.\u00a0Votre maison est le monde.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00ab&rsquo;.\u00a0.\u00a0.\u00a0Le message ira au pouvoir dans toutes les r\u00e9gions du monde, en Oregon, en Europe, en Australie, dans les \u00eeles de la mer, \u00e0 toutes les nations, langues et peuples.<\/span><\/p>\n<p><span>.\u00a0.\u00a0.\u00a0Votre foi est limit\u00e9e, elle est tr\u00e8s petite.\u00a0Votre conception de l&rsquo;\u0153uvre doit \u00eatre consid\u00e9rablement \u00e9largie.\u00a0\u00ab\u00a08<\/span><\/p>\n<p><span>En 1874, John N. Andrews est devenu le premier missionnaire adventiste officiel du septi\u00e8me jour.\u00a0Lui et ses enfants sont all\u00e9s en Suisse et trois ans plus tard, la famille John G. Matteson a \u00e9t\u00e9 envoy\u00e9e en Scandinavie.\u00a0En 1890, les missionnaires adventistes travaillaient dans 18 pays.<\/span><\/p>\n<p><span>Aujourd&rsquo;hui, sur les 238 pays du monde reconnus par les Nations Unies, les adventistes du septi\u00e8me jour ont un travail \u00e9tabli en 216.<\/span><\/p>\n<h2><strong><span>TH\u00c9OLOGIE<\/span><\/strong><\/h2>\n<p><span>Plus d&rsquo;une fois, les conseils d&rsquo;Ellen White ont emp\u00each\u00e9 l&rsquo;\u00e9glise de commettre de graves erreurs th\u00e9ologiques.\u00a0Par exemple, dans les ann\u00e9es 1890 et au d\u00e9but du XXe si\u00e8cle, le Dr John Harvey Kellogg, directeur du Battle Creek Sanitarium, a tent\u00e9 d&rsquo;introduire le panth\u00e9isme dans l&rsquo;\u00e9glise.\u00a0En 1903, lui et ses disciples, le Dr EJ Wagoner, l&rsquo;ancien AT Jones et le Dr David Paulson, arriv\u00e8rent \u00e0 Washington pour convaincre le Conseil d&rsquo;automne du Comit\u00e9 de la Conf\u00e9rence g\u00e9n\u00e9rale d&rsquo;accepter le livre de Kellogg,\u00a0<\/span><em><span>The\u00a0<\/span><\/em><em><span>Living\u00a0<\/span><\/em><em><span>Temp\u00a0<\/span><\/em><em><span>l\u00a0<\/span><\/em><em><span>e,<\/span><\/em><span>\u00a0qui avait auparavant rejet\u00e9e en raison de son contenu panth\u00e9iste.<\/span><\/p>\n<p><span>Bien que ce point ne fasse pas partie de l&rsquo;ordre du jour, \u00able travail r\u00e9gulier a \u00e9t\u00e9 mis de c\u00f4t\u00e9 et une journ\u00e9e a \u00e9t\u00e9 consacr\u00e9e \u00e0 l&rsquo;examen de la philosophie panth\u00e9iste.<\/span><\/p>\n<p><span>.\u00a0.\u00a0.\u00a0Toute la journ\u00e9e [les d\u00e9l\u00e9gu\u00e9s] se sont d\u00e9battus avec la question.\u00a0.\u00a0.\u00a0.\u00a0Vers neuf heures du soir, fr\u00e8re [AG] Daniells [le pr\u00e9sident de la Conf\u00e9rence g\u00e9n\u00e9rale, qui \u00e9tait oppos\u00e9 au livre] a estim\u00e9 qu&rsquo;il \u00e9tait temps d&rsquo;ajourner la r\u00e9union, mais il n&rsquo;a pas os\u00e9 demander un vote.\u00a0Les gens \u00e9taient trop confus et incertains, et il ne souhaitait pas faire un pas qui consoliderait les conclusions.\u00a0Il a donc renvoy\u00e9 la r\u00e9union, et les gens sont all\u00e9s \u00e0 leurs lieux d&rsquo;h\u00e9bergement.<\/span><\/p>\n<p><span>\u00abDr.\u00a0Paulson, qui soutenait fermement le Dr Kellogg, s&rsquo;est joint \u00e0 Daniells.\u00a0Pendant que les deux marchaient, ils ont poursuivi la discussion de la journ\u00e9e.\u00a0Arriv\u00e9s \u00e0 la maison o\u00f9 logeait Daniells, ils se sont tenus sous un lampadaire et ont bavard\u00e9 pendant un moment.\u00a0Enfin, le Dr Paulson a secou\u00e9 son doigt vers Daniells et a d\u00e9clar\u00e9: \u00abVous faites l&rsquo;erreur de votre vie.\u00a0Apr\u00e8s toute cette agitation, certains de ces jours, vous vous r\u00e9veillerez pour vous retrouver roul\u00e9 dans la poussi\u00e8re, et un autre dirigera les forces.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abFr\u00e8re Daniells se redressa dans sa lassitude et son d\u00e9couragement et r\u00e9pondit fermement:\u00ab Je ne crois pas \u00e0 votre proph\u00e9tie.\u00a0En tout cas, je pr\u00e9f\u00e9rerais \u00eatre roul\u00e9 dans la poussi\u00e8re \u00e0 faire ce que je crois en mon \u00e2me \u00eatre juste plut\u00f4t que de marcher avec des princes, faire ce que ma conscience me dit est mal.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abApr\u00e8s s&rsquo;\u00eatre s\u00e9par\u00e9, Daniells est entr\u00e9 dans la maison, o\u00f9 il a trouv\u00e9.\u00a0.\u00a0.\u00a0\u00abdeux messages de Mme White\u00bb [l&rsquo;attendant].\u00a0\u00bb.\u00a0.\u00a0.\u00a0Personne ne peut imaginer \u00bb, raconte Daniells,\u00ab l&#8217;empressement avec lequel j&rsquo;ai lu les documents qui nous \u00e9taient parvenus par la poste alors que nous \u00e9tions au milieu de nos discussions.\u00a0Il y a eu un t\u00e9moignage tr\u00e8s positif concernant les erreurs dangereuses qui ont \u00e9t\u00e9 enseign\u00e9es dans\u00a0<\/span><em><span>The\u00a0\u00a0<\/span><\/em><em><span>Living\u00a0\u00a0<\/span><\/em><em><span>Temple<\/span><\/em><span>\u00a0.\u00a0.\u00a0.\u00a0.\u00a0Le message \u00e9tait venu juste \u00e0 l&rsquo;heure de la crise.\u00a0En lisant, ses yeux se pos\u00e8rent sur ces mots:<\/span><\/p>\n<p><span>\u00ab&rsquo;J&rsquo;ai des choses \u00e0 dire \u00e0 nos professeurs en r\u00e9f\u00e9rence au nouveau livre\u00a0<\/span><em><span>The\u00a0<\/span><\/em><em><span>Living\u00a0<\/span><\/em><em><span>Temple<\/span><\/em><span>\u00a0.\u00a0Faites attention \u00e0 la mani\u00e8re dont vous soutenez les sentiments de ce livre concernant la personnalit\u00e9 de Dieu.\u00a0Alors que le Seigneur me pr\u00e9sente des choses, ces sentiments ne portent pas l&rsquo;approbation de Dieu.\u00a0Ils sont un pi\u00e8ge que l&rsquo;ennemi a pr\u00e9par\u00e9 ces derniers jours.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00ab&rsquo;Dans les visions de la nuit, cette affaire m&rsquo;a \u00e9t\u00e9 clairement pr\u00e9sent\u00e9e devant un grand nombre.\u00a0Une autorit\u00e9 parlait.\u00a0.\u00a0.\u00a0.\u00a0L&rsquo;orateur leva\u00a0<\/span><em><span>Living\u00a0<\/span><\/em><em><span>Temple en<\/span><\/em><span>\u00a0disant: \u00abDans ce livre, il y a des d\u00e9clarations que l&rsquo;\u00e9crivain lui-m\u00eame ne comprend pas.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abDans un autre document re\u00e7u de S\u0153ur White adress\u00e9 aux\u00ab Leaders dans notre travail m\u00e9dical \u00bb.\u00a0.\u00a0.\u00a0il lut: \u00abApr\u00e8s avoir finalement pris position, sagement, prudemment, ne faites aucune concession sur aucun point dont Dieu a clairement parl\u00e9.\u00a0Soyez aussi calme qu&rsquo;un soir d&rsquo;\u00e9t\u00e9;\u00a0mais aussi fixe que les collines \u00e9ternelles.\u00a0\u00ab\u00a09<\/span><\/p>\n<p><span>\u00abLe lendemain matin, les dirigeants de l&rsquo;\u00e9glise se sont r\u00e9unis pour leur Conseil.\u00a0Apr\u00e8s la pri\u00e8re, fr\u00e8re Daniells s&rsquo;est lev\u00e9 et a dit aux fr\u00e8res qu&rsquo;il avait re\u00e7u deux messages importants de s\u0153ur White.\u00a0Tout le monde \u00e9tait impatient de les entendre.\u00a0Ils rest\u00e8rent assis dans un silence r\u00e9fl\u00e9chi pendant qu&rsquo;il lisait.\u00a0Comme d\u00e9claration apr\u00e8s r\u00e9glage de la\u00a0d\u00e9claration de\u00a0suite la fausset\u00e9 des enseignements de\u00a0<\/span><em><span>la\u00a0<\/span><\/em><em><span>vie\u00a0<\/span><\/em><em><span>Temple\u00a0<\/span><\/em><span>\u00a0a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 l&rsquo;assembl\u00e9e, de\u00a0nombreux amen forts ont \u00e9t\u00e9 entendus et larmes coulaient librement.\u00a0C&rsquo;est \u00e0 ce moment-l\u00e0 que le vent a tourn\u00e9 \u00bbet le panth\u00e9isme a \u00e9t\u00e9 rejet\u00e9.<\/span><\/p>\n<p><span>Lorsque fr\u00e8re Daniells a envoy\u00e9 une lettre de remerciement \u00e0 Ellen White racontant les \u00e9v\u00e9nements de la journ\u00e9e, il a re\u00e7u une lettre en r\u00e9ponse dans laquelle elle expliquait pourquoi il avait \u00abre\u00e7u les messages juste au moment o\u00f9 il l&rsquo;avait fait:<\/span><\/p>\n<p><span>\u00abPeu de temps avant d&rsquo;envoyer les t\u00e9moignages dont vous avez dit qu&rsquo;ils \u00e9taient arriv\u00e9s juste \u00e0 temps, j&rsquo;avais lu un incident au sujet d&rsquo;un navire dans le brouillard rencontrant un iceberg.\u00a0.\u00a0.\u00a0.\u00a0Une nuit un\u00a0<\/span><span>la sc\u00e8ne \u00e9tait clairement pr\u00e9sent\u00e9e devant moi.\u00a0Un navire \u00e9tait sur les eaux, dans un \u00e9pais brouillard.\u00a0Soudain, le guetteur a cri\u00e9: \u00ab\u00a0Iceberg juste devant!\u00a0\u00bb\u00a0L\u00e0, au-dessus du navire, se trouvait un gigantesque iceberg.\u00a0Une voix autoritaire a cri\u00e9: \u00ab\u00a0Rencontrez-le!\u00a0\u00bb\u00a0Il n&rsquo;y eut pas un instant d&rsquo;h\u00e9sitation.\u00a0C&rsquo;\u00e9tait le moment de l&rsquo;action instantan\u00e9e.\u00a0L&rsquo;ing\u00e9nieur s&rsquo;est mis \u00e0 plein r\u00e9gime et l&rsquo;homme au volant a conduit le navire droit dans l&rsquo;iceberg.\u00a0Avec un accident, elle a heurt\u00e9 la glace.\u00a0Il y eut un choc terrible, et l&rsquo;iceberg se brisa en plusieurs morceaux, tombant avec un bruit comme le tonnerre sur le pont.\u00a0Les passagers ont \u00e9t\u00e9 violemment secou\u00e9s par la force de la collision, mais aucune vie n&rsquo;a \u00e9t\u00e9 perdue.\u00a0Le navire a \u00e9t\u00e9 bless\u00e9, mais pas irr\u00e9parable.\u00a0Elle rebondit du contact, tremblant de la tige \u00e0 la poupe comme une cr\u00e9ature vivante.\u00a0Puis elle a avanc\u00e9 sur son chemin.<\/span><\/p>\n<p><span>\u00ab&rsquo;Eh bien, je connaissais la signification de cette repr\u00e9sentation.\u00a0J&rsquo;avais mes commandes.\u00a0.\u00a0.\u00a0.<\/span><\/p>\n<p><span>\u00abC&rsquo;est pourquoi vous avez re\u00e7u les t\u00e9moignages lorsque vous l&rsquo;avez fait.\u00a0Cette nuit-l\u00e0, j&rsquo;\u00e9tais debout \u00e0 une heure, \u00e9crivant aussi vite que ma main pouvait passer sur le papier.\u00a0\u00ab\u00a0dix<\/span><\/p>\n<h2><strong>CONCLUSION<\/strong><\/h2>\n<p><span>Dieu a utilis\u00e9 Ellen White \u00e0 plusieurs reprises pour diriger l&rsquo;\u00e9glise \u00e0 travers diff\u00e9rentes crises.\u00a0Bien qu&rsquo;elle soit d\u00e9c\u00e9d\u00e9e en 1915, ses \u00e9crits continuent de guider la direction de l&rsquo;\u00e9glise face \u00e0 de nouveaux d\u00e9fis.\u00a0Par cons\u00e9quent, ses \u00e9crits sont toujours d&rsquo;actualit\u00e9.\u00a0\u00abCroyez au Seigneur votre Dieu, ainsi vous serez affermis;\u00a0croyez ses proph\u00e8tes, ainsi vous prosp\u00e9rerez \u00bb(\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/kjv1900\/2%20Chron.%2020.20\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"2 Chron. 20.20\" data-version=\"kjv1900\" data-purpose=\"bible-reference\"><span>2 Chron. 20:20, LSG<\/span><\/a><span>\u00a0).<\/span><\/p>\n<p><span>1 Ellen G.White,\u00a0\u00a0<\/span><em><span>Early\u00a0\u00a0<\/span><\/em><em><span>W\u00a0<\/span><\/em><em><span>ritings\u00a0<\/span><\/em><span>\u00a0(Washington, DC: Review and Herald Pub. Assn., 1945), 97, 100.<\/span><\/p>\n<p><span>2 Ellen G.White,\u00a0\u00a0<\/span><em><span>Vie\u00a0\u00a0<\/span><\/em><em><span>S\u00a0<\/span><\/em><em><span>ketches\u00a0\u00a0<\/span><\/em><em><span>d&rsquo;\u00a0\u00a0<\/span><\/em><em><span>Ellen\u00a0\u00a0<\/span><\/em><em><span>G.\u00a0<\/span><\/em><em><span>W\u00a0<\/span><\/em><em><span>Hite<\/span><\/em><span>\u00a0(Mountain View, CA:.. Pacific Press Pub Assn, 1915), 125.<\/span><\/p>\n<p><span>3 Ellen G.White,\u00a0\u00a0<\/span><em><span>S\u00a0<\/span><\/em><em><span>\u00e9lus\u00a0\u00a0<\/span><\/em><em><span>Messages\u00a0<\/span><\/em><span>\u00a0(Washington, DC:.. Revue et Pub Herald Assoc, 1980), 3: 280.<\/span><\/p>\n<p><span>4 Ellen G. White,\u00a0\u00a0<\/span><em><span>Testimonies\u00a0\u00a0<\/span><\/em><em><span>for\u00a0\u00a0<\/span><\/em><em><span>the\u00a0\u00a0<\/span><\/em><em><span>C\u00a0<\/span><\/em><em><span>h\u00a0<\/span><\/em><em><span>urch\u00a0<\/span><\/em><span>\u00a0(MountainView, Californie: Pacific Press Pub. Assn., 1948), 1: 489\u201392.<\/span><\/p>\n<p><span>5 Ellen G.White,\u00a0\u00a0<\/span><em><span>Fundamentals\u00a0\u00a0<\/span><\/em><em><span>of\u00a0\u00a0<\/span><\/em><em><span>Christian\u00a0\u00a0<\/span><\/em><em><span>Education<\/span><\/em><span>\u00a0(Nashville, TN: Southern Pub. Assn., 1923), 45, 46.<\/span><\/p>\n<p><span>6 Uriah Smith, \u00abNote de la r\u00e9daction\u00bb,\u00a0<\/span><em><span>A\u00a0<\/span><\/em><em><span>dvent\u00a0\u00a0<\/span><\/em><em><span>Review\u00a0\u00a0<\/span><\/em><em><span>et\u00a0\u00a0<\/span><\/em><em><span>S\u00a0<\/span><\/em><em><span>abbath\u00a0<\/span><\/em><em><span>Herald<\/span><\/em><span>\u00a0, 3 f\u00e9vrier 1859,\u00a0<em>p\u00a0<\/em>\u00a0. 87.<\/span><\/p>\n<p><span>7 Blanc,\u00a0\u00a0<em>bouchons\u00a0<\/em><\/span><em><span>Life\u00a0\u00a0<\/span><\/em><em><span>S<\/span><\/em><span>\u00a0, 205.<\/span><\/p>\n<p>8 Ibid., 208, 209.<\/p>\n<p><span>9 Arthur L. White,\u00a0\u00a0<\/span><em><span>Ellen G. White<\/span><\/em><span>\u00a0&#8211;\u00a0<\/span><em><span>Les premi\u00e8res ann\u00e9es d&rsquo;Elmshaven:\u00a0\u00a0<\/span><\/em><em><span>1900-1905\u00a0\u00a0<\/span><\/em><span>(Washington, DC: Review and Herald Pub. Assn., 1981), 5: 296-298.<\/span><\/p>\n<p>10 Ibid., 299, 301.<\/p>\n<p><strong>Auteur<\/strong>: Gerhard Pfandl, PhD, maintenant \u00e0 la retraite, a \u00e9t\u00e9 directeur associ\u00e9 du Biblical Research Institute, Silver Spring, Maryland, \u00c9tats-Unis.<\/p>\n<p><strong>Source<\/strong>: Ministry Magazine<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Gerhard Pfandl, PhD. Quelques mots sur la mani\u00e8re dont les ann\u00e9es de formation de l&rsquo;\u00c9glise adventiste du septi\u00e8me jour ont \u00e9t\u00e9 influenc\u00e9es par l&rsquo;une de ses fondatrices, Ellen G. White. Les contributions de Ellen G. White \u00e0 l&rsquo;\u00c9glise adventiste du septi\u00e8me jour ont \u00e9t\u00e9 inestimables dans de nombreux domaines et tout au long de [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2754,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[220,218],"tags":[404,1157,1156],"aioseo_notices":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2752"}],"collection":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/comments?post=2752"}],"version-history":[{"count":1,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2752\/revisions"}],"predecessor-version":[{"id":2753,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2752\/revisions\/2753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media\/2754"}],"wp:attachment":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media?parent=2752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/categories?post=2752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/tags?post=2752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}