{"id":2741,"date":"2020-11-11T22:34:24","date_gmt":"2020-11-11T22:34:24","guid":{"rendered":"https:\/\/www.adventdesk.com\/home\/?p=2741"},"modified":"2020-11-11T22:34:24","modified_gmt":"2020-11-11T22:34:24","slug":"le-don-des-langues","status":"publish","type":"post","link":"https:\/\/www.adventdesk.com\/home\/le-don-des-langues\/","title":{"rendered":"Le don des langues"},"content":{"rendered":"<p>Par EARLE HILGERT,<\/p>\n<p><span><span class=\"\">Le sujet du don des langues et du don de l&rsquo;interpr\u00e9tation des langues tel que pr\u00e9sent\u00e9 dans\u00a0<\/span><\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/1%20Cor%2012.10\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"1 Cor 12.10\" data-version=\"esv\" data-purpose=\"bible-reference\"><span><span class=\"\">1 Corinthiens 12:10<\/span><\/span><\/a><span><span class=\"\">\u00a0peut \u00eatre divis\u00e9 en deux parties.\u00a0<\/span>Le premier concerne la question de la d\u00e9finition de ce don telle qu&rsquo;elle se trouve dans l&rsquo;\u00c9glise primitive;\u00a0et la seconde concerne la question de savoir si un tel don existe ou non dans l&rsquo;\u00e9glise aujourd&rsquo;hui.<\/span><\/p>\n<p><!--more--><\/p>\n<p><span>En ce qui concerne le texte grec de\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/1%20Cor%2012.10\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"1 Cor 12.10\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>1 Corinthiens 12:10<\/span><\/a><span>\u00a0, la premi\u00e8re expression consid\u00e9r\u00e9e est le\u00a0<\/span><em><span>gene glossOn,<\/span><\/em><span>\u00a0traduit dans la version King James \u00ab\u00a0genres de langues\u00a0\u00bb, avec le mot \u00ab\u00a0divers\u00a0\u00bb fourni.\u00a0Ceci est traduit dans la version standard r\u00e9vis\u00e9e de la m\u00eame mani\u00e8re, sauf que la langue est \u00e0 jour: \u00abdivers types de langues\u00bb.\u00a0La deuxi\u00e8me expression impliqu\u00e9e est\u00a0<\/span><em><span>hermeneia glasson,<\/span><\/em><span>\u00a0\u00abl&rsquo;interpr\u00e9tation des langues\u00bb.<\/span><\/p>\n<p><span>Un mot peut \u00eatre dit \u00e0 propos de\u00a0<\/span><em><span>glosson,<\/span><\/em><span>\u00a0le pluriel g\u00e9nitif de\u00a0<\/span><em><span>glossa,<\/span><\/em><span>\u00a0\u00ablangue\u00bb.\u00a0Ce mot appara\u00eet cinquante fois dans le Nouveau Testament et est utilis\u00e9 \u00e0 la fois pour le membre lui-m\u00eame et aussi pour ce qu&rsquo;il produit, la langue, comme dans l&rsquo;expression \u00abparent\u00e9, langue et peuple\u00bb.\u00a0Il ne fait aucun doute que dans le texte consid\u00e9r\u00e9, le mot signifie le son oral ou la langue.<\/span><\/p>\n<p><span>Il n&rsquo;y a rien dans le grec, en ce qui concerne ces expressions, qui pose probl\u00e8me.\u00a0La traduction de la KJV et du RSV est ad\u00e9quate.\u00a0Il n&rsquo;y a pas non plus de variation textuelle dans les manuscrits qui soit significative en ce qui concerne le sens.<\/span><\/p>\n<h2><em><span>QUEL \u00c9TAIT CE DON?<\/span><\/em><\/h2>\n<p><span>Dans\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/Mark%2016.17\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Mark 16.17\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>Marc 16:17, le<\/span><\/a><span>\u00a0Christ est cit\u00e9 comme disant: \u00ab\u00a0Ils parleront en de nouvelles langues\u00a0\u00bb, se r\u00e9f\u00e9rant aux miracles \u00e0 accomplir par les disciples apr\u00e8s son ascension.\u00a0L&rsquo;accomplissement de cette promesse est venu quelques jours plus tard \u00e0 la Pentec\u00f4te.\u00a0Dans\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/Acts%202.4\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Acts 2.4\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>Actes 2: 4,<\/span><\/a><span> il est rapport\u00e9 que le jour de la Pentec\u00f4te \u00ab\u00a0ils furent tous remplis du Saint-Esprit et commenc\u00e8rent \u00e0 parler en d&rsquo;autres langues, comme l&rsquo;Esprit leur donna de s&rsquo;exprimer\u00a0\u00bb. Il y avait des Juifs \u00e0 J\u00e9rusalem de \u00abtoutes les nations sous le ciel\u00bb, et \u00abchacun les entendait parler dans sa propre langue\u00bb.<\/span><\/p>\n<p><span>Le don donn\u00e9 \u00e0 la Pentec\u00f4te \u00e9tait un don de parole et non un don d&rsquo;\u00e9coute de la part des juifs pr\u00e9sents. Ceci est indiqu\u00e9 par le fait que cela s&rsquo;appelle le don des langues.\u00a0Il est venu \u00abcomme l&rsquo;Esprit leur a donn\u00e9 la parole\u00bb, non comme les Juifs ont \u00e9t\u00e9 entendus.<\/span><\/p>\n<p><span>Le fait qu&rsquo;ils parlent \u00ab\u00a0comme l&rsquo;Esprit leur a donn\u00e9 de s&rsquo;exprimer\u00a0\u00bb indique \u00e9galement que le ph\u00e9nom\u00e8ne n&rsquo;\u00e9tait pas simplement une r\u00e9action humaine \u00e0 l&rsquo;impact de la pr\u00e9sence du Saint-Esprit. Les actions des disciples \u00e0 cette \u00e9poque \u00e9taient directement sous le contr\u00f4le du Saint-Esprit.\u00a0La parole aussi bien que l&rsquo;impulsion \u00e9taient dues \u00e0 l&rsquo;Esprit.\u00a0De plus, ils parlaient dans des langues r\u00e9elles comprises par les juifs non palestiniens pr\u00e9sents.\u00a0Que ce soient des dialectes locaux plut\u00f4t que du grec, ce qui aurait sans doute \u00e9t\u00e9 compris par la majorit\u00e9 pr\u00e9sente, est sous-entendu les nombreuses localit\u00e9s mentionn\u00e9es.<\/span><\/p>\n<p><span>\u00c0 propos de cette manifestation, Ellen G. White \u00e9crit:<\/span><\/p>\n<blockquote><p><span>\u00abChaque langue connue \u00e9tait repr\u00e9sent\u00e9e par ceux qui \u00e9taient assembl\u00e9s. Cette diversit\u00e9 de langues aurait \u00e9t\u00e9 un grand obstacle \u00e0 l&rsquo;annonce de l&rsquo;\u00c9vangile; Dieu a donc combl\u00e9 d&rsquo;une mani\u00e8re miraculeuse la carence des ap\u00f4tres. Le Saint-Esprit a fait pour eux ce qu&rsquo;ils pouvaient Ils pouvaient maintenant proclamer les v\u00e9rit\u00e9s de l&rsquo;\u00c9vangile \u00e0 l&rsquo;\u00e9tranger, en parlant avec exactitude les langues de ceux pour lesquels ils travaillaient. \u00ab\u00a0&#8211; Les\u00a0<\/span><em><span>Actes<\/span><\/em><span>\u00a0des\u00a0<\/span><em><span>Ap\u00f4tres,<\/span><\/em><span>\u00a0pp. 39, 40.<\/span><\/p><\/blockquote>\n<p><span>Ce don a non seulement affect\u00e9 l&rsquo;utilisation des langues \u00e9trang\u00e8res, mais a \u00e9galement purifi\u00e9 leur utilisation de l&rsquo;aram\u00e9en natif.\u00a0\u00abA partir de ce moment, la langue des disciples \u00e9tait pure, simple et exacte, qu&rsquo;ils parlent leur langue maternelle ou dans une langue \u00e9trang\u00e8re.\u00bb &#8211; Ibid., P.\u00a040. C&rsquo;\u00e9tait un signe aussi bien qu&rsquo;un t\u00e9moignage: \u00ab\u00a0Ce don miraculeux \u00e9tait une preuve solide pour le monde que leur commission portait le sceau du Ciel.\u00a0\u00bb\u00a0<\/span><em><span>\u2014Ibid.<\/span><\/em><\/p>\n<h2 class=\"WordSection2\"><em><span>PIERRE ET CORNEILLE<\/span><\/em><\/h2>\n<p class=\"WordSection2\"><span>La preuve suivante du don des langues \u00e9tait l&rsquo;exp\u00e9rience de Pierre avec la famille de Corneille, enregistr\u00e9e dans\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/Acts%2010\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Acts 10\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>Actes 10<\/span><\/a><span>\u00a0.\u00a0Les versets 45 et 46 d\u00e9clarent: \u00ab\u00a0Tous les fid\u00e8les circoncis qui \u00e9taient venus avec Pierre furent \u00e9tonn\u00e9s de ce que le don du Saint-Esprit \u00e9tait aussi r\u00e9pandu sur les pa\u00efens. Car ils les entendaient parler en langues et glorifier Dieu. \u00ab\u00a0<\/span><\/p>\n<p><span>Il n&rsquo;y a aucune raison de croire que le don des langues dans ce cas \u00e9tait essentiellement diff\u00e9rent de ce qu&rsquo;il \u00e9tait parmi les disciples le jour de la Pentec\u00f4te.\u00a0Il y avait une tr\u00e8s bonne raison pour laquelle la maison de Corneille devait parler en langues ce jour-l\u00e0, car ceux qui \u00e9taient venus avec Pierre ne croyaient pas qu&rsquo;un Gentil pouvait recevoir le don du Saint-Esprit.\u00a0Comme \u00e0 la Pentec\u00f4te, donc ici, c&rsquo;\u00e9tait un signe et un t\u00e9moignage pour les chr\u00e9tiens juifs qui n&rsquo;\u00e9taient pas pr\u00eats \u00e0 accepter les Gentils dans l&rsquo;\u00e9glise.\u00a0Bien que l&rsquo;on ne sache pas quelle langue ils parlaient, il ne serait pas d\u00e9raisonnable de supposer qu&rsquo;ils ont \u00e9clat\u00e9 en aram\u00e9en ou en h\u00e9breu, car cela aurait le plus impressionn\u00e9 les chr\u00e9tiens juifs sceptiques.<\/span><\/p>\n<h2><em><span>LES CONVERTIS D&rsquo;APOLLOS<\/span><\/em><\/h2>\n<p><span>L&rsquo;instance suivante enregistr\u00e9e du don des langues dans l&rsquo;\u00e9glise primitive \u00e9tait parmi les convertis d&rsquo;Apollos \u00e0 \u00c9ph\u00e8se.\u00a0Apollos avait baptis\u00e9 ses convertis avec le bapt\u00eame de Jean, et quand Paul est venu \u00e0 \u00c9ph\u00e8se, il a demand\u00e9 \u00e0 ces croyants s&rsquo;ils avaient re\u00e7u le don du Saint-Esprit.\u00a0Quand ils ont r\u00e9pondu que non, il les a instruits et les a baptis\u00e9s au nom du Seigneur J\u00e9sus.\u00a0Alors Paul leur imposa les mains;\u00a0ils re\u00e7urent le don du Saint-Esprit, proph\u00e9tis\u00e8rent et parl\u00e8rent en langues.\u00a0Encore une fois, rien n&rsquo;indique que le don donn\u00e9 ici \u00e9tait essentiellement diff\u00e9rent du don de la Pentec\u00f4te.\u00a0On ne sait pas s&rsquo;il y avait des personnes pr\u00e9sentes qui ont compris les phrases qui venaient des l\u00e8vres de ces convertis lorsqu&rsquo;ils ont re\u00e7u le cadeau.\u00a0On ne sait pas quelles langues ils parlaient.<\/span><\/p>\n<p><span>Que ce don \u00e9tait un langage r\u00e9el, qu&rsquo;il a continu\u00e9 avec ces hommes, et qu&rsquo;il a \u00e9t\u00e9 donn\u00e9 dans un but est indiqu\u00e9 par Ellen G.White:<\/span><\/p>\n<p><span>\u00abIls ont ensuite \u00e9t\u00e9 baptis\u00e9s au nom de J\u00e9sus;\u00a0et comme Paul \u00ableur imposa les mains\u00bb, ils re\u00e7urent aussi le bapt\u00eame du Saint-Esprit, qui leur permit de parler les langues des autres nations et de proph\u00e9tiser.\u00a0Ainsi, ils \u00e9taient qualifi\u00e9s pour travailler comme missionnaires \u00e0 \u00c9ph\u00e8se et ses environs, et aussi pour aller proclamer l&rsquo;\u00c9vangile en Asie Mineure. \u00ab\u00a0&#8211; The\u00a0<\/span><em><span>Review and Herald,<\/span><\/em><span>\u00a031 ao\u00fbt 1911.<\/span><\/p>\n<p><span>Essentiellement, le cadeau ici \u00e9tait identique\u00a0<\/span><em><span>au<\/span><\/em><span>\u00a0cadeau du jour de la Pentec\u00f4te.<\/span><\/p>\n<h2><em><span>LE PROBL\u00c8ME \u00c0 CORINTHE<\/span><\/em><\/h2>\n<p><span>L&rsquo;autre r\u00e9f\u00e9rence au don des langues dans le Nouveau Testament se trouve dans la premi\u00e8re \u00e9p\u00eetre aux Corinthiens, dont le texte qui est le centre de cette \u00e9tude fait partie.<\/span><\/p>\n<p><span>1 Corinthiens, chapitres 12-14, constituent une unit\u00e9. L&rsquo;un des principaux sujets ici est le don des langues et l&rsquo;interpr\u00e9tation des langues.\u00a0Cela semble avoir \u00e9t\u00e9 \u00e9crit peu de temps apr\u00e8s que Paul eut eu son exp\u00e9rience avec les convertis d&rsquo;Apollos.\u00a0De toute \u00e9vidence, on a trop insist\u00e9 sur le don des langues dans l&rsquo;\u00e9glise de Corinthe, et Paul \u00e9tait impatient de remettre les choses en ordre \u00e0 cet \u00e9gard.<\/span><\/p>\n<p><span>Le chapitre 12 commence par une r\u00e9f\u00e9rence au c\u0153ur du probl\u00e8me &#8211; les dons spirituels.\u00a0Paul semble avoir ici particuli\u00e8rement \u00e0 l&rsquo;esprit le don des langues, car au verset 3 il mentionne l&rsquo;homme\u00a0<\/span><em><span>en pneumati theou talon,<\/span><\/em><span>\u00a0\u00ab\u00a0qui parle dans l&rsquo;Esprit de Dieu\u00a0\u00bb &#8211; expression presque identique \u00e0 celle utilis\u00e9e au chapitre 14: 2 concernant le don des langues.\u00a0Tout au long du douzi\u00e8me chapitre, Paul s&rsquo;attarde sur l&rsquo;image globale des dons dans l&rsquo;\u00e9glise, car son d\u00e9sir est de montrer que ce don des langues qui \u00e9tait si soulign\u00e9 n&rsquo;\u00e9tait pas le don le plus important donn\u00e9 par Dieu \u00e0 son peuple.\u00a0Il met l&rsquo;accent sur la grande vari\u00e9t\u00e9 de dons, qui proviennent tous du m\u00eame Esprit, et pr\u00e9cise que l&rsquo;un ne doit pas \u00eatre plac\u00e9 au-dessus de l&rsquo;autre.<\/span><\/p>\n<p><span>Paul ouvre le treizi\u00e8me chapitre en se r\u00e9f\u00e9rant \u00e0 nouveau aux langues, et continue en montrant que l&rsquo;amour est encore plus grand que ce don.\u00a0Les langues cesseront et la proph\u00e9tie passera, mais l&rsquo;amour restera (verset 8).<\/span><\/p>\n<p><span>Enfin, dans le quatorzi\u00e8me chapitre, l&rsquo;ap\u00f4tre est confront\u00e9 au vrai probl\u00e8me, le don des langues.\u00a0Le fardeau de Paul est qu&rsquo;il doit \u00eatre utilis\u00e9 pour le bien commun.<\/span><\/p>\n<p><span>Jusqu&rsquo;\u00e0 pr\u00e9sent, rien n&rsquo;indique que le don ici \u00e0 Corinthe \u00e9tait en aucune fa\u00e7on diff\u00e9rent du don qui \u00e9tait apparu \u00e0 la Pentec\u00f4te ou dans la famille de Corneille ou \u00e0 \u00c9ph\u00e8se.\u00a0Maintenant, cependant, Paul fait une distinction s\u00e9rieuse entre le don des langues et la proph\u00e9tie (versets 2-5), ce qui semble \u00e9trange parce que jusqu&rsquo;ici ils avaient \u00e9t\u00e9 mentionn\u00e9s presque comme synonymes.\u00a0\u00c0 la Pentec\u00f4te, lorsque les ap\u00f4tres ont \u00e9t\u00e9 accus\u00e9s d&rsquo;\u00eatre ivres, Pierre a cit\u00e9 des d\u00e9clarations de l&rsquo;Ancien Testament indiquant que le don de proph\u00e9tie serait ressuscit\u00e9 et a d\u00e9fendu le don des langues sur cette base (\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/Acts%202.17\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Acts 2.17\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>Actes 2:17<\/span><\/a><span>\u00a0).\u00a0Mais ici, Paul fait une distinction entre les deux.\u00a0Quelle \u00e9tait donc cette manifestation dans l&rsquo;\u00e9glise corinthienne?<\/span><\/p>\n<p><span>Il existe au moins deux th\u00e9ories.\u00a0La premi\u00e8re est que cette manifestation \u00e9tait identique au don de la Pentec\u00f4te &#8211; des langues r\u00e9elles donn\u00e9es pour la pr\u00e9dication de l&rsquo;\u00c9vangile.\u00a0L&rsquo;autre th\u00e9orie est qu&rsquo;il s&rsquo;agissait d&rsquo;\u00e9nonc\u00e9s extatiques, de sons qui ne repr\u00e9sentaient aucun langage r\u00e9el, mais qui \u00e9taient une r\u00e9action involontaire \u00e0 la pr\u00e9sence du Saint-Esprit.\u00a0Il est soulign\u00e9 que l&rsquo;\u00e9glise de Corinthe \u00e9tait en grande partie une \u00e9glise pa\u00efenne.\u00a0Ses membres \u00e9taient\u00a0<\/span><em><span>venus<\/span><\/em><span>hors des religions pa\u00efennes o\u00f9 ils avaient \u00e9t\u00e9 familiaris\u00e9s avec de tels \u00e9nonc\u00e9s, qui \u00e9taient consid\u00e9r\u00e9s comme une langue des dieux et \u00e9taient interpr\u00e9t\u00e9s comme des oracles, soit par la personne qui parlait, soit par une autre personne.\u00a0Il est expliqu\u00e9 que ces chr\u00e9tiens pa\u00efens avaient amen\u00e9 dans l&rsquo;\u00e9glise avec eux une psychologie adapt\u00e9e \u00e0 de telles r\u00e9actions, et lorsque le Saint-Esprit est venu sur eux, le r\u00e9sultat \u00e9tait ce \u00e0 quoi ils s&rsquo;\u00e9taient habitu\u00e9s lorsqu&rsquo;ils \u00e9taient pa\u00efens.<\/span><\/p>\n<p><span>Il y a des difficult\u00e9s dans ces deux th\u00e9ories.\u00a0En ce qui concerne l&rsquo;opinion selon laquelle le don \u00e9tait le m\u00eame que celui donn\u00e9 \u00e0 la Pentec\u00f4te, Ellen G. White indique que les disciples y ont acquis une comp\u00e9tence qui a rendu possible la poursuite de l&rsquo;\u00e9vang\u00e9lisation.\u00a0Mais Paul dit des choses de la manifestation corinthienne qui sont difficiles \u00e0 concilier avec l&rsquo;exp\u00e9rience pentec\u00f4tiste.\u00a0\u00abCar si je prie dans une langue inconnue, mon esprit prie, mais ma compr\u00e9hension est infructueuse\u00bb (verset 14).\u00a0\u00abPourtant, dans l&rsquo;\u00e9glise, j&rsquo;aurais pr\u00e9f\u00e9r\u00e9 dire cinq mots avec mon intelligence, afin que par ma voix je puisse aussi enseigner aux autres, puis dix mille mots dans une langue inconnue\u00bb (verset 19).<\/span><\/p>\n<p><span>En ce qui concerne la th\u00e9orie extatique, il faut souligner que la m\u00eame terminologie est utilis\u00e9e ici que dans le r\u00e9cit du don \u00e0 la Pentec\u00f4te (comparer\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/Acts%202.4\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"Acts 2.4\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>Actes 2: 4<\/span><\/a><span>\u00a0et\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/1%20Cor.%2012.10\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"1 Cor. 12.10\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>1 Cor. 12:10<\/span><\/a><span>\u00a0).\u00a0Si la manifestation \u00e9tait vraiment si diff\u00e9rente \u00e0 Corinthe, pourquoi Paul utilise-t-il ici le m\u00eame mot que celui utilis\u00e9 \u00e0 plusieurs reprises dans les Actes?\u00a0Il semble \u00e9galement tr\u00e8s difficile de comprendre comment un charabia extatique pourrait \u00eatre consid\u00e9r\u00e9 comme une r\u00e9action \u00e0 la puissance du Saint-Esprit.<\/span><\/p>\n<h2><em><span>UNE SOLUTION SUGG\u00c9R\u00c9E<\/span><\/em><\/h2>\n<p><span>S&rsquo;il n&rsquo;est probablement pas possible de parvenir \u00e0 une r\u00e9ponse d\u00e9finitive \u00e0 ce probl\u00e8me, les suggestions provisoires suivantes semblent offrir au moins\u00a0<\/span><em><span>une<\/span><\/em><span>\u00a0solution partielle.<\/span><\/p>\n<p><span>Premi\u00e8rement, rien dans\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/1%20Cor%2014\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"1 Cor 14\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>1 Corinthiens 14<\/span><\/a><span>\u00a0n&rsquo;indique que le don n&rsquo;\u00e9tait pas un langage r\u00e9el qui pourrait \u00eatre utilis\u00e9 dans les efforts d&rsquo;\u00e9vang\u00e9lisation.\u00a0La d\u00e9claration de l&rsquo;ap\u00f4tre selon laquelle \u00ables langues sont un signe, non pour ceux qui croient, mais pour ceux qui ne croient pas\u00bb (\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/1%20Cor.%2014.22\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"1 Cor. 14.22\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>1 Cor. 14:22<\/span><\/a><span>\u00a0), semblerait impliquer qu&rsquo;ils \u00e9taient des langues r\u00e9elles.\u00a0Le don d&rsquo;une langue r\u00e9elle serait certainement un signe plus significatif pour un incroyant que le charabia.<\/span><\/p>\n<p><span>Deuxi\u00e8mement, le don de Corinthe n&rsquo;\u00e9tait pas enti\u00e8rement identique \u00e0 celui de la Pentec\u00f4te.\u00a0Cela semble \u00e9vident parce que ceux qui l&rsquo;ont manifest\u00e9 parlaient parfois sans savoir ce qu&rsquo;ils disaient (versets 13-15).\u00a0Cela \u00e9tait profitable \u00e0 l&rsquo;\u00e9glise s&rsquo;il y avait quelqu&rsquo;un pr\u00e9sent qui pouvait comprendre.\u00a0M\u00eame s&rsquo;il n&rsquo;y en avait pas, il pourrait encore y avoir une b\u00e9n\u00e9diction pour celui qui a parl\u00e9, car il est raisonnable de croire que lorsque le Saint-Esprit \u00e9tait sur un homme, il recevrait lui-m\u00eame une b\u00e9n\u00e9diction du fait m\u00eame de sa pr\u00e9sence.\u00a0Paul se r\u00e9f\u00e8re \u00e0 ceci: \u00ab\u00a0Celui qui parle dans une langue inconnue s&rsquo;\u00e9difie lui-m\u00eame\u00a0\u00bb (verset 4).<\/span><\/p>\n<p><span>Troisi\u00e8mement, \u00e0 cause de ces diff\u00e9rences, un autre cadeau a \u00e9t\u00e9 donn\u00e9, l&rsquo;interpr\u00e9tation des langues.\u00a0Quand il y avait des personnes pr\u00e9sentes qui comprenaient, il n&rsquo;y avait pas besoin de ce don.\u00a0\u00c0 d&rsquo;autres moments, un message serait transmis de fa\u00e7on spectaculaire \u00e0 une \u00e9glise dans une langue \u00e9trang\u00e8re et une autre personne en recevrait l&rsquo;interpr\u00e9tation.\u00a0Le m\u00eame don pourrait \u00eatre utilis\u00e9 pour pr\u00eacher l&rsquo;\u00c9vangile.\u00a0Si quelqu&rsquo;un qui ne parlait pas la langue locale venait dans une \u00e9glise avec un message, et qu&rsquo;un autre fr\u00e8re avait le don de l&rsquo;interpr\u00e9tation, ce dernier pourrait aider \u00e0 la pr\u00e9sentation de ce message.\u00a0Ce don d&rsquo;interpr\u00e9tation peut \u00e9galement avoir inclus l&rsquo;explication et l&rsquo;application du message donn\u00e9.<\/span><\/p>\n<p><span>Ce qui a \u00e9t\u00e9 dit peut \u00eatre r\u00e9sum\u00e9 comme suit: Le don des langues fait r\u00e9f\u00e9rence \u00e0 la capacit\u00e9 de parler une langue sous la pr\u00e9sence et l&rsquo;influence du Saint-Esprit.\u00a0Cela peut faire r\u00e9f\u00e9rence \u00e0 la langue de l&rsquo;orateur ou \u00e0 une langue qu&rsquo;il ne connaissait pas auparavant.\u00a0Comme \u00e0 la Pentec\u00f4te, l&rsquo;orateur peut \u00eatre conscient de la signification de \u00abce qu&rsquo;il dit;\u00a0ou comme \u00e0 Corinthe, cela peut lui \u00eatre parfois inintelligible.\u00a0Le don de l&rsquo;interpr\u00e9tation est un don apparent\u00e9, la capacit\u00e9 de comprendre et d&rsquo;interpr\u00e9ter une langue que l&rsquo;interpr\u00e8te n&rsquo;a pas apprise naturellement.<\/span><\/p>\n<h2><em><span>CES DONS EXISTENT-ILS DANS L&rsquo;\u00c9GLISE AUJOURD&rsquo;HUI?<\/span><\/em><\/h2>\n<p><span>La pr\u00e9sence de ces dons dans l&rsquo;\u00c9glise apostolique pose naturellement la question de savoir s&rsquo;ils existent dans l&rsquo;\u00c9glise aujourd&rsquo;hui.\u00a0D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, la r\u00e9ponse doit \u00eatre non. Tr\u00e8s t\u00f4t dans l&rsquo;histoire chr\u00e9tienne, le don des langues, avec les autres dons de l&rsquo;Esprit, a \u00e9t\u00e9 perdu pour l&rsquo;\u00e9glise.\u00a0Le seul t\u00e9moignage clair de la pr\u00e9sence de ce don apr\u00e8s les jours des ap\u00f4tres est une d\u00e9claration faite par Ir\u00e9n\u00e9e, qui a \u00e9crit dans le sud de la Gaule vers la fin du deuxi\u00e8me si\u00e8cle.\u00a0<\/span><em><span>(H\u00e9r\u00e9sies,<\/span><\/em><span>\u00a0livre V, chapitre 6.) \u00c0 la fin du quatri\u00e8me si\u00e8cle, Jean Chrysostome a t\u00e9moign\u00e9 concernant\u00a0<\/span><a class=\"rtBibleRef\" href=\"https:\/\/biblia.com\/bible\/esv\/1%20Cor%2012\" target=\"_blank\" rel=\"noopener noreferrer\" data-reference=\"1 Cor 12\" data-version=\"esv\" data-purpose=\"bible-reference\"><span>1 Corinthiens 12<\/span><\/a><span>\u00a0:<\/span><\/p>\n<p><span>\u00abTout cet endroit est tr\u00e8s obscur: mais l&rsquo;obscurit\u00e9 est produite par notre ignorance des faits \u00e9voqu\u00e9s et par leur cessation, \u00e9tant tels qu&rsquo;ils se produisaient alors mais maintenant n&rsquo;ont plus lieu.\u00bb &#8211; Hom\u00e9lie 29, \u00e0\u00a0<\/span><em><span>Nic\u00e8ne et PEW- Nicene Fathers,<\/span><\/em><span>\u00a01\u00e8re s\u00e9rie, vol.\u00a012, p.\u00a0168.<\/span><\/p>\n<p><span>Que tel soit le cas n&rsquo;est pas surprenant compte tenu de l&rsquo;apostasie qui est entr\u00e9e si t\u00f4t dans l&rsquo;\u00c9glise.\u00a0D\u00e8s le deuxi\u00e8me si\u00e8cle, ceux qui avaient les dons de l&rsquo;Esprit tomb\u00e8rent en discr\u00e9dit et furent remplac\u00e9s dans la direction de l&rsquo;\u00e9glise par les\u00a0<\/span><em><span>officiers \u00e9lus, les \u00e9v\u00eaques<\/span><\/em><span>\u00a0et\u00a0<\/span><em><span>les<\/span><\/em><span>\u00a0pr\u00eatres.<\/span><\/p>\n<p><span>De nos jours, Dieu n&rsquo;a pas r\u00e9tabli ce don en g\u00e9n\u00e9ral, ni sous sa forme pentec\u00f4tiste ni sous sa forme corinthienne.\u00a0Parfois, des histoires sont re\u00e7ues du champ de mission de cas isol\u00e9s o\u00f9 un missionnaire a pu parler une langue qu&rsquo;il n&rsquo;avait pas apprise, ou o\u00f9 un natif \u00e9tait capable de comprendre une langue qu&rsquo;il ne connaissait pas.\u00a0Ces exp\u00e9riences surviennent g\u00e9n\u00e9ralement en temps de crise.\u00a0Ils sont souvent tr\u00e8s difficiles \u00e0 v\u00e9rifier.\u00a0Sans aucun doute, de telles providences peuvent se produire et se produisent, mais leur manifestation ne semble pas \u00eatre identique \u00e0 celle du Nouveau Testament.<\/span><\/p>\n<p><span>Il y a une raison logique \u00e0 cela.\u00a0Tout comme la science m\u00e9dicale a rendu inutile la pr\u00e9sence d&rsquo;un don permanent de gu\u00e9rison, la condition r\u00e9pandue de l&rsquo;\u00c9glise chr\u00e9tienne a rendu possible\u00a0<\/span><em><span>la<\/span><\/em><span>\u00a0diffusion de l&rsquo;\u00a0<\/span><em><span>\u00c9vangile<\/span><\/em><span>\u00a0par\u00a0<\/span><em><span>ceux<\/span><\/em><span>\u00a0qui parlent naturellement les langues de la terre.\u00a0Le don de gu\u00e9rison et le don des langues ne sont d\u00e9sormais accord\u00e9s qu&rsquo;en temps de crise, lorsque les installations ordinaires sont soit inad\u00e9quates, soit indisponibles.\u00a0La pr\u00e9dication de l&rsquo;\u00c9vangile dans plus de mille langues, et du message du troisi\u00e8me ange dans plus de sept cents, est un accomplissement de l&rsquo;\u0153uvre pour laquelle le don des langues a \u00e9t\u00e9 donn\u00e9 \u00e0 l&rsquo;\u00c9glise primitive.<\/span><\/p>\n<p><span>\u00c9crivant d&rsquo;Europe en 1886, o\u00f9 elle avait parl\u00e9 par l&rsquo;interm\u00e9diaire d&rsquo;interpr\u00e8tes dans de nombreuses langues, es Ellen G. White a d\u00e9clar\u00e9:<\/span><\/p>\n<p><span>\u00ab\u00a0C&rsquo;est avec un d\u00e9sir ardent que j&rsquo;attends avec impatience le moment o\u00f9 les \u00e9v\u00e9nements du jour de la Pentec\u00f4te se r\u00e9p\u00e9teront avec une puissance encore plus grande qu&rsquo;\u00e0 cette occasion &#8230; Alors, comme \u00e0 la saison de la Pentec\u00f4te, le peuple entendra la v\u00e9rit\u00e9 qui leur a \u00e9t\u00e9 dit, chacun dans sa propre langue &#8230; Des milliers de voix seront impr\u00e9gn\u00e9es du pouvoir de dire les merveilleuses v\u00e9rit\u00e9s de la parole de Dieu. La langue balbutiante sera lib\u00e9r\u00e9e, et les timides seront rendus forts. \u00ab\u00a0&#8211; The\u00a0<\/span><em><span>Review and Herald,<\/span><\/em><span>\u00a020 juillet 1886.<\/span><\/p>\n<section class=\"footnotes\">\n<h2>Note:<\/h2>\n<p><span>Il s&rsquo;agissait d&rsquo;une pr\u00e9sentation faite devant la facult\u00e9 et les \u00e9tudiants du s\u00e9minaire th\u00e9ologique, r\u00e9pondant aux exigences du cours de Licence en th\u00e9ologie.<\/span><\/p>\n<p>Auteur: EARLE HILGERT, instructeur en th\u00e9ologie biblique et syst\u00e9matique, SDA Theological Seminary<\/p>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Par EARLE HILGERT, Le sujet du don des langues et du don de l&rsquo;interpr\u00e9tation des langues tel que pr\u00e9sent\u00e9 dans\u00a01 Corinthiens 12:10\u00a0peut \u00eatre divis\u00e9 en deux parties.\u00a0Le premier concerne la question de la d\u00e9finition de ce don telle qu&rsquo;elle se trouve dans l&rsquo;\u00c9glise primitive;\u00a0et la seconde concerne la question de savoir si un tel don [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[220,218],"tags":[1150,1151],"aioseo_notices":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2741"}],"collection":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/comments?post=2741"}],"version-history":[{"count":1,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2741\/revisions"}],"predecessor-version":[{"id":2742,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/2741\/revisions\/2742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media\/2743"}],"wp:attachment":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media?parent=2741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/categories?post=2741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/tags?post=2741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}