{"id":1212,"date":"2019-07-01T20:46:57","date_gmt":"2019-07-01T20:46:57","guid":{"rendered":"https:\/\/www.adventdesk.com\/home\/?p=1212"},"modified":"2019-07-01T20:46:57","modified_gmt":"2019-07-01T20:46:57","slug":"racisme-et-nationalisme-lenseignement-biblique","status":"publish","type":"post","link":"https:\/\/www.adventdesk.com\/home\/racisme-et-nationalisme-lenseignement-biblique\/","title":{"rendered":"Racisme et nationalisme : l\u2019enseignement biblique"},"content":{"rendered":"<p><main class=\"layout-version-1\"><\/p>\n<div class=\"wrapper\">\n<p class=\"byline\">Elias Brasil de Souza<\/p>\n<p class=\"subhead\">Toute manifestation de racisme, d\u2019ethnocentrisme, de nationalisme, de tribalisme ou d\u2019esprit de caste est inacceptable, non seulement d\u2019un point de vue humanitaire, mais aussi d\u2019une perspective biblique.<\/p>\n<p>Dans notre monde contemporain, le racisme et le nationalisme demeurent des d\u00e9fis de taille. Malheureusement, ces probl\u00e8mes affectent aussi l\u2019\u00c9glise et invalident son privil\u00e8ge, \u00eatre le sel de la terre. Dans cet essai, nous aborderons le probl\u00e8me du racisme et du nationalisme d\u2019une perspective biblique\u00a0; puis nous exposerons des principes permettant d\u2019y faire face.<\/p>\n<p><!--more--><\/p>\n<p>Quelle est la d\u00e9finition habituelle des mots \u00ab\u00a0race\u00a0\u00bb et \u00ab\u00a0nation\u00a0\u00bb\u00a0? Une source donne cette d\u00e9finition\u00a0: \u00ab\u00a0Un groupe ou une cat\u00e9gorie de personnes li\u00e9es par une origine commune.\u00a0\u00bb<sup>1<\/sup>\u00a0Une autre indique que le concept de race pourrait inclure certaines diff\u00e9rences physiques pouvant distinguer un groupe humain d\u2019un autre, mais pr\u00e9cise que la connaissance scientifique actuelle a \u00e9tabli \u00ab\u00a0que les diversit\u00e9s reconnues chez les \u00eatres humains ne sont pas fond\u00e9es sur une d\u00e9finition biologique de leur race\u00a0\u00bb<sup>2<\/sup>. En r\u00e9alit\u00e9, cette affirmation est clairement confirm\u00e9e par le fait que \u00ab\u00a0tous les groupes humains partagent le m\u00eame type de sang, sont inter-fertiles, et peuvent recevoir et donner des organes malgr\u00e9 les pr\u00e9tendues limites raciales\u00a0\u00bb<sup>3<\/sup>. Selon l\u2019usage qui en est fait dans cet essai, la race et l\u2019ethnicit\u00e9<sup>4<\/sup>\u00a0sont virtuellement synonymes, et cette derni\u00e8re, en termes de peuples anciens, pourrait \u00eatre minimalement d\u00e9finie \u00ab\u00a0en tant que groupe identitaire\u00a0\u00bb<sup>5<\/sup>.<\/p>\n<p>De m\u00eame, le concept de nation a \u00e9t\u00e9 d\u00e9fini en tant que \u00ab\u00a0vaste corps d\u2019individus unis par une descendance, une histoire, une culture ou une langue communes, et habitant dans un pays ou un territoire particulier\u00a0\u00bb<sup>6<\/sup>. Les termes \u00ab\u00a0racisme\u00a0\u00bb et \u00ab\u00a0nationalisme\u00a0\u00bb d\u00e9rivent de ces deux concepts. Le racisme \u00ab\u00a0d\u00e9signe en fait deux choses tr\u00e8s diff\u00e9rentes. D\u2019une part, c\u2019est une question de comportement, g\u00e9n\u00e9ralement une manifestation de haine ou de m\u00e9pris envers des individus dont les caract\u00e9ristiques physiques bien d\u00e9finies diff\u00e8rent des siennes propres\u00a0; d\u2019autre part, c\u2019est une id\u00e9ologie, une doctrine concernant les races humaines.\u00a0\u00bb<sup>7<\/sup>\u00a0Le nationalisme, lui, peut \u00eatre d\u00e9fini comme \u00e9tant \u00ab\u00a0un sentiment de solidarit\u00e9 collective au sein de limites g\u00e9ographiques et culturelles identifi\u00e9es\u00a0\u00bb<sup>8<\/sup>\u00a0; toutefois il arrive souvent qu\u2019il se d\u00e9veloppe en une id\u00e9ologie exclusiviste, dans la mesure o\u00f9 il pose comme principe la sup\u00e9riorit\u00e9 d\u2019une nation sur une autre, ou d\u2019un groupe de personnes sur un autre. Aux fins de cet essai, nous consid\u00e9rerons le nationalisme, le racisme et m\u00eame le tribalisme comme les \u00e9l\u00e9ments du m\u00eame probl\u00e8me\u00a0: la difficult\u00e9 des humains \u00e0 accepter \u00ab\u00a0l\u2019autre\u00a0\u00bb ethnique ou culturel.<\/p>\n<h2>Race et nation dans la Bible<\/h2>\n<p>Tout d\u2019abord, veillons \u00e0 ne pas appliquer aux \u00c9critures les notions modernes de racisme ou de nationalisme. Elles sont, en effet, \u00e9trang\u00e8res aux \u00e9crivains bibliques. N\u00e9anmoins, le nationalisme ou le racisme dans le sens o\u00f9 certaines cultures s\u2019estimaient sup\u00e9rieures \u00e0 d\u2019autres constituait certainement un probl\u00e8me aux temps bibliques. Pour les Grecs, les \u00e9trangers qui ignoraient la langue et la culture grecques \u00e9taient des barbares\u00a0; pour les Juifs, les non-Juifs \u00e9taient des pa\u00efens<sup>9<\/sup>. En outre, l\u2019Ancien Testament utilise des termes communs pour transmettre l\u2019id\u00e9e de race ou d\u2019ethnie. Il s\u2019agit de\u00a0<i>g\u00f4y<\/i>\u00a0(555 fois) et de\u00a0<i>\u2018am<\/i>\u00a0(1 866 fois). En d\u00e9pit d\u2019un chevauchement consid\u00e9rable,\u00a0<i>g\u00f4y<\/i>\u00a0d\u00e9signe des nations et des individus en tant qu\u2019entit\u00e9s politiques et sociales, alors que\u00a0<i>\u2018am<\/i>\u00a0souligne la parent\u00e9 et se r\u00e9f\u00e8re le plus souvent \u00e0 Isra\u00ebl en tant que peuple de Dieu<sup>10<\/sup>. Le Nouveau Testament utilise\u00a0<i>ethnos<\/i>\u00a0(164 fois) et\u00a0<i>laos<\/i>\u00a0(143 fois) pour indiquer des peuples ou des nations. Dans l\u2019usage actuel, cependant,\u00a0<i>ethnos<\/i>\u00a0se r\u00e9f\u00e8re davantage aux nations, aux pa\u00efens, aux incroyants et m\u00eame aux chr\u00e9tiens de la gentilit\u00e9<sup>11<\/sup>, attendu que\u00a0<i>laos<\/i>\u00a0tend \u00e0 d\u00e9signer le peuple de Dieu<sup>12<\/sup>, comme\u00a0<i>\u2018am<\/i>\u00a0dans l\u2019Ancien Testament. On note \u00e9galement deux autres termes\u00a0:\u00a0<i>phy<\/i>l<i>\u02dce<\/i>\u00a0(31 fois), ce terme signifiant race ou tribu et se r\u00e9f\u00e9rant \u00e9ventuellement aux 12 tribus d\u2019Isra\u00ebl (historiquement, ou m\u00e9taphoriquement aux chr\u00e9tiens), ou aux tribus de la terre, dans le sens de peuples et de nations<sup>13<\/sup>. Le second, genos (21 fois), v\u00e9hicule la notion de famille et de pays, entre autres, ce qui par cons\u00e9quent peut avoir des connotations ethniques.<\/p>\n<p>Ces donn\u00e9es linguistiques examin\u00e9es, tournons-nous maintenant vers ce qui a \u00e9t\u00e9 appel\u00e9 la \u00ab\u00a0Table des peuples\u00a0\u00bb (Gn 10), laquelle fournit une vue d\u2019ensemble des peuples et des groupes ethniques au d\u00e9but de l\u2019histoire du monde. Un examen approfondi de cette table indique que la vari\u00e9t\u00e9 de nations et de peuples constitue la toile de fond des promesses subs\u00e9quentes selon lesquelles les nations de la terre seraient b\u00e9nies<sup>14<\/sup>. Les avantages d\u2019une diversit\u00e9 de groupes ethniques et de nations semblent avoir \u00e9t\u00e9 impliqu\u00e9s dans ce mandat\u00a0: remplir la terre (Gn 9.2). Ceci peut expliquer partiellement pourquoi les b\u00e2tisseurs de la tour de Babel subirent le jugement de Dieu (Gn 11.1-9)\u00a0: ils se rebell\u00e8rent contre l\u2019ordre divin de remplir la terre. En confondant leurs langues et en les dispersant sur la face de la terre, Dieu permit la diversit\u00e9 des familles, des nations et des groupes ethniques qui, finalement, remplirent la terre. Par la suite, il appela Abraham \u00e0 \u00eatre en b\u00e9n\u00e9diction \u00e0 \u00ab\u00a0toutes les familles de la terre\u00a0\u00bb (Gn 12.3).<\/p>\n<p>Il faut \u00e9galement mentionner un aspect int\u00e9ressant du plan divin, inclusif et souverain, pour le monde entier\u00a0: Dieu n\u2019accorda pas seulement des territoires \u00e0 Isra\u00ebl, mais aussi \u00e0 d\u2019autres nations. Il donna des possessions territoriales \u00e0 \u00c9sa\u00fc (Dt 2.5), aux Moabites (Dt 2.9) et aux Ammonites (2.19). Amos \u00e9crit que le Seigneur agit dans l\u2019int\u00e9r\u00eat d\u2019autres nations un peu comme lors de l\u2019Exode\u00a0: il fit sortir les Philistins de Caphtor et les Syriens de Kir (Am 9.7, LSG). De plus, Deut\u00e9ronome 32.8 r\u00e9it\u00e8re\u00a0: \u00ab\u00a0Quand le Tr\u00e8s-Haut donna un h\u00e9ritage aux nations, quand il s\u00e9para les enfants des hommes, il fixa les limites des peuples d\u2019apr\u00e8s le nombre des enfants d\u2019Isra\u00ebl.\u00a0\u00bb Les proph\u00e8tes classiques pr\u00e9dirent le jour o\u00f9 les nations viendraient \u00e0 J\u00e9rusalem adorer le Seigneur et d\u00e9couvrir ses lois (voir Jr 50.5\u00a0; Za 8.21-23\u00a0; 14.16-21).<\/p>\n<p>En revanche, il faut convenir que l\u2019Ancien Testament contient aussi des oracles de jugement contre les nations. Cependant, on ne trouve dans ces messages aucune trace de pr\u00e9jug\u00e9s ethniques ou raciaux. En fait, Isra\u00ebl et Juda furent souvent l\u2019objet des jugements divins les plus s\u00e9v\u00e8res (par ex., Am 7.8,15\u00a0; 8.2). Les nations ne furent pas jug\u00e9es en raison de leur diff\u00e9rence ethnique ou raciale, mais sur la base de leur loyaut\u00e9 envers l\u2019alliance divine \u00e9ternelle<sup>15<\/sup>. Les identit\u00e9s nationales, raciales ou ethniques ne sont \u00e9valu\u00e9es n\u00e9gativement nulle part dans la Bible. L\u2019\u00e9lection d\u2019Abraham et de ses descendants en tant que peuple sp\u00e9cial de Dieu ne se produisit pas au d\u00e9triment des nations, tel qu\u2019indiqu\u00e9 plus haut. Contre toute attente (Dt 7.7\u00a0; 26.5), Abraham, et plus tard, Isra\u00ebl, re\u00e7urent la mission d\u2019\u00eatre en b\u00e9n\u00e9diction \u00e0 toutes les familles de la terre.<\/p>\n<h2>R\u00e9flexion th\u00e9ologique sur la diversit\u00e9 ethnique<\/h2>\n<p>Ainsi, la Bible mentionne non seulement des races, des nations et des groupes ethniques, mais r\u00e9v\u00e8le aussi que Dieu s\u2019implique activement en faveur des nations et des familles dans le d\u00e9roulement du plan du salut. En fait, le texte biblique offre des principes et des directives permettant de faire face aux d\u00e9fis que posent le racisme et le nationalisme.<\/p>\n<p>Premi\u00e8rement, Dieu cr\u00e9a l\u2019humanit\u00e9 \u00e0 partir d\u2019un seul couple. C\u2019est l\u00e0 un principe fondamental. Par cons\u00e9quent, la cr\u00e9ation n\u2019accorde aucune place \u00e0 la sup\u00e9riorit\u00e9 d\u2019un groupe par rapport \u00e0 un autre, puisque la \u00ab\u00a0doctrine de la cr\u00e9ation confirme l\u2019unit\u00e9 aussi bien que la dignit\u00e9 de toute l\u2019humanit\u00e9\u00a0\u00bb<sup>16<\/sup>. Au-del\u00e0 de la vari\u00e9t\u00e9 et de la diversit\u00e9 des cultures, des soci\u00e9t\u00e9s, des races et des nationalit\u00e9s s\u2019\u00e9l\u00e8ve le fait que tous ont \u00e9t\u00e9 cr\u00e9\u00e9s \u00e0 l\u2019image de Dieu. En d\u00e9finitive, \u00ab\u00a0il n\u2019existe pas une multiplicit\u00e9 de races humaines, mais une seule race humaine\u00a0\u00bb<sup>17<\/sup>.<\/p>\n<p>Deuxi\u00e8mement, la chute a non seulement affect\u00e9 la relation entre Dieu et l\u2019humanit\u00e9, mais elle a aussi creus\u00e9 un foss\u00e9 entre les \u00eatres humains (Rm 3.23\u00a0; 1.20-26). Plus les diff\u00e9rents groupes ethniques s\u2019\u00e9loignent de Dieu, plus ils acqui\u00e8rent des visions du monde aboutissant au racisme, au nationalisme et \u00e0 l\u2019ethnocentrisme \u2013 avec, pour cons\u00e9quences naturelles, l\u2019oppression et la destruction de \u00ab\u00a0l\u2019autre\u00a0\u00bb. Au lieu d\u2019admirer la magnifique tapisserie de la diversit\u00e9 culturelle et ethnique, certains font de leur propre personne et de leur propre culture la norme selon laquelle les autres doivent \u00eatre mesur\u00e9s. De telles pr\u00e9tentions sont \u00e0 la base du racisme, de l\u2019ethnocentrisme et du nationalisme qui ont nui si gravement au peuple de Dieu \u00e0 des moments pr\u00e9cis de l\u2019histoire.<\/p>\n<p>Troisi\u00e8mement, les promesses eschatologiques de Dieu incluent les nations. \u00c9sa\u00efe et Amos d\u00e9crivent les nations\u00a0<i>(g\u00f4y<\/i>) et les peuples (<i>\u2018amm\u00eem<\/i>) comme affluant \u00e0 J\u00e9rusalem pour d\u00e9couvrir les voies de Dieu (Es 2.1-4\u00a0; Am 2.1,2). \u00c9sa\u00efe pr\u00e9dit aussi qu\u2019un jour un autel sera \u00e9rig\u00e9 dans le pays d\u2019\u00c9gypte et que les \u00c9gyptiens serviront le Seigneur (Es 19.19-22). Le proph\u00e8te annonce \u00e9galement que l\u2019\u00c9gypte, l\u2019Assyrie et Isra\u00ebl seront un, et applique \u00e0 l\u2019\u00c9gypte comme \u00e0 l\u2019Assyrie le langage contractuel auparavant r\u00e9serv\u00e9 \u00e0 Isra\u00ebl<sup>18<\/sup>. L\u2019\u00c9gypte est appel\u00e9e \u00ab\u00a0[mon] peuple\u00a0\u00bb (<i>\u2018am\u00ee<\/i>\u00a0\u2013 Es 10.24\u00a0; 43.6,7\u00a0; Os 1.10\u00a0; 2.23\u00a0; Jr 11.4), et l\u2019Assyrie, \u00ab\u00a0l\u2019\u0153uvre de mes mains\u00a0\u00bb (<i>ma\u2019seh yaday<\/i>\u00a0\u2013 Es 60.21\u00a0;64.8\u00a0; Ps 119.73\u00a0; 138.8). Enfin, \u00c9sa\u00efe 56.6 promet l\u2019int\u00e9gration de l\u2019\u00e9tranger (<i>nekar<\/i>) dans la communaut\u00e9 de l\u2019alliance.<\/p>\n<p>De m\u00eame, le Nouveau Testament repr\u00e9sente l\u2019\u00c9vangile pr\u00each\u00e9 \u00e0 toutes les nations (<i>ethnos<\/i>) de la terre (Mt 13.10\u00a0; 24.14\u00a0; 28.19\u00a0; Lc 24.47). Des \u00e2mes issues de nations hostiles au message du salut (Ap 11.18\u00a0; 14.8\u00a0; 17.15\u00a0; 18.3) acceptent le royaume de Dieu. Dans le d\u00e9nouement eschatologique, toutes les nations sont repr\u00e9sent\u00e9es parmi les saints (Rm 1.5,6\u00a0; Ap 15.4\u00a0; 21.24) et marchent \u00e0 la lumi\u00e8re \u00e9manant de Dieu et de l\u2019Agneau (Ap 21.24).<\/p>\n<p>Quatri\u00e8mement, la Bible reconna\u00eet et agr\u00e9e la diversit\u00e9 des races et des nations qui peuplent la terre (Gn 10.1-32\u00a0; Dt 32.8). De plus, l\u2019effusion de l\u2019Esprit lors de la Pentec\u00f4te confirme le plan de Dieu pour tous les peuples, langues et cultures (Ac 2). Les identit\u00e9s ethniques, nationales ou tribales cr\u00e9ent un sentiment de parent\u00e9 et de communaut\u00e9. Elles aident les \u00eatres humains \u00e0 satisfaire leurs besoins de s\u00e9curit\u00e9 et d\u2019appartenance. Cette sorte de diversit\u00e9 stimule et favorise aussi la cr\u00e9ativit\u00e9 et l\u2019enrichissement humains<sup>19<\/sup>.<\/p>\n<p>Cinqui\u00e8mement, les nations et les groupes ethniques ne sont pas des entit\u00e9s absolues. Aussi importantes et utiles soient-elles dans l\u2019\u00e9tat actuel du monde, les entit\u00e9s pr\u00e9cit\u00e9es \u00ab\u00a0sont des communaut\u00e9s historiques en dehors de l\u2019ordre cr\u00e9\u00e9 original. Elles sont, par cons\u00e9quent, des communaut\u00e9s provisionnelles et contingentes ne pouvant revendiquer aucune loyaut\u00e9 humaine ultime.\u00a0\u00bb<sup>20<\/sup>\u00a0En outre, les entit\u00e9s raciales et nationales \u2013 aussi significatives semblent-elles \u00eatre \u2013 portent les cons\u00e9quences du p\u00e9ch\u00e9. La conscience de cette r\u00e9alit\u00e9 devrait nous pousser \u00e0 d\u00e9fier le nationalisme, le tribalisme, le racisme et tous les types d\u2019idol\u00e2trie ethnique. La Bible subordonne clairement tout statut bas\u00e9 sur la race ou la nationalit\u00e9 \u00e0 la seigneurie absolue de J\u00e9sus. En Christ, toutes les barri\u00e8res \u00e9rig\u00e9es par le p\u00e9ch\u00e9 sont d\u00e9molies\u00a0: \u00ab\u00a0Il n\u2019y a plus ni Juif ni Grec, il n\u2019y a plus ni esclave ni libre, il n\u2019y a plus ni homme ni femme\u00a0; car tous vous \u00eates un en J\u00e9sus-Christ.\u00a0\u00bb<sup>21<\/sup>\u00a0(Ga 3.28)<\/p>\n<p>Sixi\u00e8mement, Dieu n\u2019admet ni ne tol\u00e8re les pr\u00e9jug\u00e9s raciaux ou ethniques. Voici un \u00e9pisode qui semble refl\u00e9ter un pr\u00e9jug\u00e9 ethnique\u00a0: \u00ab\u00a0Marie et Aaron parl\u00e8rent contre Mo\u00efse au sujet de la femme \u00e9thiopienne qu\u2019il avait prise, car il avait pris une femme \u00e9thiopienne.\u00a0\u00bb (Nb 12.1) L\u2019identit\u00e9 ethnique de la femme de Mo\u00efse \u00e9tait devenue un probl\u00e8me pour Marie et Aaron \u2013 un pr\u00e9texte, sans doute, pour camoufler leur ambition secr\u00e8te\u00a0: partager le leadership avec Mo\u00efse (ceci n\u2019a rien de nouveau\u00a0: un parti int\u00e9ress\u00e9 pr\u00e9texte une excuse ethnique pour atteindre un but douteux). Dieu r\u00e9agit imm\u00e9diatement en frappant Marie d\u2019une l\u00e8pre \u00ab\u00a0blanche comme la neige\u00a0\u00bb (Nb 12.10). La le\u00e7on qui se d\u00e9gage de cet \u00e9pisode est claire\u00a0: Dieu ne fait pas acception de personnes, de nationalit\u00e9s ou d\u2019identit\u00e9s ethniques.<\/p>\n<p>Septi\u00e8mement, Dieu est impartial. Cette d\u00e9claration pourtant claire n\u2019a peut-\u00eatre pas \u00e9t\u00e9 \u00e9vidente \u00e0 l\u2019\u00e9poque. L\u2019\u00c9glise primitive elle-m\u00eame ne la comprenait pas pleinement. La preuve, c\u2019est que Pierre dut recevoir une vision pour comprendre que Dieu ne fait pas preuve de discrimination sur la base de l\u2019ethnie. Voici ce que Pierre d\u00e9clara \u00e0 Corneille, qui avait r\u00e9uni sa parent\u00e9 et ses amis\u00a0: \u00ab\u00a0En v\u00e9rit\u00e9, je reconnais que Dieu ne fait point acception de personnes\u00a0\u00bb (Ac 10.34). Chose int\u00e9ressante, le verbe \u00ab\u00a0reconnais\u00a0\u00bb indique un processus, c\u2019est-\u00e0-dire que Pierre admit qu\u2019il n\u2019avait pas encore acquis une compr\u00e9hension totale et absolue, mais \u00e9tait sur la voie de saisir cette v\u00e9rit\u00e9 profonde et fondamentale.<\/p>\n<p>Par la suite, les dirigeants chr\u00e9tiens durent convoquer un concile pour discuter de la situation des pa\u00efens convertis. Apr\u00e8s l\u2019\u00e9tude de la Bible et la pri\u00e8re, ils inclurent les gentils convertis au christianisme sans les forcer d\u2019\u00eatre circoncis et de suivre l\u2019ensemble des lois c\u00e9r\u00e9monielles. (Ac 15). Cependant, malgr\u00e9 cette vision donn\u00e9e \u00e0 Pierre et la d\u00e9cision prise lors du Concile de J\u00e9rusalem, les probl\u00e8mes ne disparurent pas, h\u00e9las\u00a0! Paul fut constamment en butte aux factions et aux divisions au sein m\u00eame de l\u2019\u00c9glise, certaines \u00e9tant sans doute suscit\u00e9es par des pr\u00e9jug\u00e9s ethniques ou nationalistes. Pierre lui-m\u00eame retomba plus tard dans ses anciens pr\u00e9jug\u00e9s (Ga 2.11,12). Certaines \u00e9p\u00eetres du Nouveau Testament \u2013 aux Galates, aux \u00c9ph\u00e9siens et aux Colossiens<sup>22<\/sup>\u00a0\u2013 soulignent que les Juifs et les gentils \u00e9taient des membres \u00e9gaux du corps de J\u00e9sus-Christ. Ceci indique que les questions d\u2019ethnicit\u00e9 continuaient \u00e0 d\u00e9fier l\u2019\u00c9glise primitive.<\/p>\n<h2>R\u00e9ponses bibliques au racisme et au nationalisme<\/h2>\n<p>\u00c0 la lumi\u00e8re de ce qui pr\u00e9c\u00e8de, notons que de graves distorsions des vues bibliques sur la race et la nationalit\u00e9 surgissent lorsque l\u2019identification d\u2019un individu avec sa nation, son pays, sa tribu ou son groupe ethnique entra\u00eene de l\u2019hostilit\u00e9 envers d\u2019autres groupes. Selon Miroslav Volf, une telle hostilit\u00e9, qu\u2019il \u00e9tiquette \u00ab\u00a0exclusion\u00a0\u00bb, se manifeste de trois mani\u00e8res\u00a0: l\u2019\u00e9limination, la domination ou l\u2019abandon<sup>23<\/sup>. Mais comment contrecarrer ces probl\u00e8mes d\u2019exclusion\u00a0? Nous disposons de trois moyens.<\/p>\n<p><b>La bienveillance<\/b>. Les \u00c9critures remplacent l\u2019\u00e9limination par la bienveillance. Le commandement \u00ab\u00a0Tu aimeras ton prochain\u00a0\u00bb (Lv 19.18\u00a0; Mc 12.31) transcende certainement les fronti\u00e8res tribales et nationales, et inclut \u00ab\u00a0l\u2019autre\u00a0\u00bb tribal, ethnique, ou national. \u00c9lis\u00e9e, par exemple, ne consid\u00e9ra pas le commandant syrien comme un ennemi \u00e0 \u00e9liminer, mais comme son prochain ayant besoin d\u2019\u00eatre gu\u00e9ri (2 R 5.9-19). On observe une recommandation analogue dans les Proverbes\u00a0: \u00ab\u00a0Si ton ennemi a faim, donne-lui du pain \u00e0 manger\u00a0; s\u2019il a soif, donne-lui de l\u2019eau \u00e0 boire. Car ce sont des charbons ardents que tu amasses sur sa t\u00eate, et l\u2019\u00c9ternel te r\u00e9compensera.\u00a0\u00bb (Pr 25.21,22) Et Paul dit\u00a0: \u00ab\u00a0Ne te laisse pas vaincre par le mal, mais surmonte le mal par le bien.\u00a0\u00bb (Rm 12.21) La bienveillance \u00ab\u00a0\u00e9limine\u00a0\u00bb l\u2019ennemi en en faisant un ami.<\/p>\n<p><b>Le service.<\/b>\u00a0Les \u00c9critures recommandent le service au lieu de la domination. On le lit dans la l\u00e9gislation en faveur de l\u2019\u00e9tranger\u00a0: \u00ab\u00a0Tu ne maltraiteras point l\u2019\u00e9tranger [<i>g\u02dcer<\/i>], et tu ne l\u2019opprimeras point\u00a0; car vous avez \u00e9t\u00e9 \u00e9trangers dans le pays d\u2019\u00c9gypte.\u00a0\u00bb (Ex 22.21) Dieu \u00e9voque l\u2019exp\u00e9rience d\u2019Isra\u00ebl en \u00c9gypte et en fait une source de motivation quant \u00e0 l\u2019observation de la loi. Puisque l\u2019opprim\u00e9 peut \u00e0 son tour devenir l\u2019oppresseur, Dieu rappelle \u00e0 son peuple son ancien statut afin qu\u2019il manifeste un esprit de solidarit\u00e9 envers l\u2019\u00e9tranger. Parmi les nations de l\u2019ancien Proche-Orient, les Isra\u00e9lites \u00e9taient les seuls que leurs lois mettaient dans l\u2019obligation de prot\u00e9ger les \u00e9trangers (<i>g\u02dcer\u00eem<\/i>)<sup>24<\/sup>. Et \u00e0 une \u00e9poque o\u00f9 les Juifs g\u00e9missaient sous l\u2019oppression romaine, J\u00e9sus enseigna une autre mani\u00e8re d\u2019agir\u00a0: \u00ab\u00a0Si quelqu\u2019un te frappe sur la joue droite, pr\u00e9sente-lui aussi l\u2019autre.\u00a0\u00bb (Mt 5.41)<\/p>\n<p><b>La solidarit\u00e9.<\/b>\u00a0L\u2019abandon de \u00ab\u00a0l\u2019autre\u00a0\u00bb ethnique doit \u00eatre remplac\u00e9 par la solidarit\u00e9. Lors de la d\u00e9dicace du temple, Salomon pria Dieu d\u2019entendre la pri\u00e8re de l\u2019\u00e9tranger (1 R 8.41,43), ce qui indique que les services du temple incluraient les \u00e9trangers \u2013 et non leur exclusion comme cela se produisit plus tard. Dans ce contexte, la parabole du bon Samaritain est riche d\u2019enseignement, puisqu\u2019elle d\u00e9crit un \u00ab\u00a0exemple classique de racisme\u00a0\u00bb<sup>25<\/sup>. Au fil de l\u2019histoire, un pr\u00eatre, puis un L\u00e9vite, passent outre la victime gisant sur la route. Finalement, c\u2019est un Samaritain \u2013 \u00ab\u00a0l\u2019autre\u00a0\u00bb ethnique \u2013 qui procure la gu\u00e9rison au voyageur gri\u00e8vement bless\u00e9. Contrairement \u00e0 d\u2019autres paraboles, celle du bon Samaritain donne un exemple, \u00e0 accepter ou \u00e0 rejeter. Chose ironique, le mod\u00e8le par excellence n\u2019est pas personnifi\u00e9 par le pr\u00eatre ou le L\u00e9vite \u2013 des fonctionnaires du temple \u2013 mais par un Samaritain incarnant la volont\u00e9 de Dieu sur la mani\u00e8re de traiter \u00ab\u00a0l\u2019autre\u00a0\u00bb ethnique (Lc 10.29-37).<\/p>\n<p>Ainsi, les \u00c9critures nous incitent \u00e0 adopter une attitude d\u2019acceptation, de service, et de solidarit\u00e9 dans nos relations avec notre prochain d\u2019une autre ethnie. C\u2019est bien s\u00fbr plus facile \u00e0 dire qu\u2019\u00e0 faire. La purification ethnique et les conflits de nature raciale ont entach\u00e9 de sang le XXe si\u00e8cle (en fait, l\u2019histoire humaine tout enti\u00e8re). Des actes horribles perp\u00e9tr\u00e9s par une entit\u00e9 ethnique contre une autre font encore souffrir\u00a0; la perte de personnes, de cultures et de propri\u00e9t\u00e9s br\u00fblent toujours dans la m\u00e9moire collective des nations ou des tribus. Ne minimisons pas la profondeur d\u2019une telle souffrance. Mais en m\u00eame temps, souvenons-nous que la gr\u00e2ce et le pardon demeurent les seules options viables pour une gu\u00e9rison et une restauration permanentes.<\/p>\n<h2>Conclusion<\/h2>\n<p>La Bible sanctionne la diversit\u00e9 des races et des nations. Elle d\u00e9clare que toutes les races, tous les groupes ethniques et toutes les nations forment une seule et m\u00eame famille humaine. Sur ce fondement th\u00e9ologique, la Bible \u00e9rige sa perception des nations et des groupes ethniques\u00a0; elle relativise les distinctions tribales et nationales. Et au-dessus de ces loyaut\u00e9s, se situe la loyaut\u00e9 absolue que nous devons au Dieu cr\u00e9ateur, lui qui nous enjoint de traiter l&rsquo;\u00e9tranger en fr\u00e8re ou soeur. Par cons\u00e9quent, toute manifestation de racisme, d\u2019ethnocentrisme, de nationalisme, de tribalisme ou d\u2019esprit de caste est inacceptable, non seulement d\u2019un point de vue humanitaire, mais aussi d\u2019une perspective biblique ou th\u00e9ologique.<\/p>\n<p>Seule une vision du monde model\u00e9e par les \u00c9critures peut susciter le fondement solide permettant d\u2019aborder de fa\u00e7on pratique des sujets tels que la race, l\u2019ethnicit\u00e9 et la nationalit\u00e9. Comme la Bible l\u2019affirme clairement d\u00e8s le \u00ab\u00a0commencement\u00a0\u00bb, la cr\u00e9ation constitue le fondement de nos relations avec notre prochain \u00e9tranger. En outre, les \u00c9critures r\u00e9v\u00e8lent que le p\u00e9ch\u00e9 a d\u00e9form\u00e9 notre perception de l\u2019autre. Le racisme et autres formes de pr\u00e9jug\u00e9s ont infect\u00e9 la nature humaine. Seul le sang de J\u00e9sus peut les \u00e9radiquer. \u00ab\u00a0Il n\u2019y a ni Grec ni Juif, ni circoncis ni incirconcis, ni barbare ni Scythe, ni esclave ni libre\u00a0; mais Christ est tout et en tous.\u00a0\u00bb (Col 3.11)<\/p>\n<p class=\"about\">Elias Brasil de Souza est directeur adjoint de l\u2019Institut de recherche biblique \u00e0 la Conf\u00e9rence g\u00e9n\u00e9rale des adventistes du septi\u00e8me jour, \u00e0 Silver Spring, Maryland (\u00c9tats-Unis). Son courriel\u00a0:\u00a0souzae@gc.adventist.org.<\/p>\n<p>Cet article, l\u00e9g\u00e8rement abr\u00e9g\u00e9, est tir\u00e9 de la version publi\u00e9e d\u2019un article ayant paru dans le bulletin de l\u2019Institut de recherche biblique (BRI). Avec permission.<\/p>\n<h2>Citation recommand\u00e9e<\/h2>\n<p>Elias Brasil de Souza, \u00ab Racisme et nationalisme\u00a0: l\u2019enseignement biblique \u00bb,\u00a0<i>Dialogue<\/i>\u00a026 (2014\/2), p. 5-8, 35<\/p>\n<h2>R\u00e9f\u00e9rences<\/h2>\n<section class=\"references\">\n<ol>\n<li>Ernest Cashmore, Michael Banton et Heribert Adam,\u00a0<i>Dictionary of Race and Ethnic Relations,<\/i>\u00a03<sup>e<\/sup>\u00a0\u00e9d., Londres, Routledge, 1994, p. 294.<\/li>\n<li>Robert Miles, \u00ab\u00a0Nationalism\u00a0\u00bb, dans Guido Bolaffi, Raffaele Bracalenti, Peter Braham et Sandro Gindro, \u00e9ds.,\u00a0<i>Dictionary of Race, Ethnicity and Culture,<\/i>\u00a0Londres, SAGE Publications, 2003, p. 240.<\/li>\n<li>J. Andrew Kirk, \u00ab\u00a0Race, Class, Caste and the Bible\u00a0\u00bb,\u00a0<i>Themelios<\/i>\u00a010:2, 1985, p. 7.<\/li>\n<li>En raison de l\u2019utilisation du mot \u00ab\u00a0race\u00a0\u00bb avec un sens biologique dans les id\u00e9ologies eug\u00e9niques et racistes, les \u00e9rudits ont eu tendance \u00e0 abandonner ce terme en faveur du terme \u00ab\u00a0ethnicit\u00e9\u00a0\u00bb, dans lequel la culture, et non la biologie, \u00e9tait la premi\u00e8re cat\u00e9gorie pour distinguer des groupes de personnes. Eric D. Barreto, \u00ab\u00a0Ethnic Negotiations: The Function of Race and Ethnicity in Acts 16\u00a0\u00bb, th\u00e8se de doctorat, Universit\u00e9 Emory, 2010, p. 38-41.<\/li>\n<li>Ann Killebrew,\u00a0<i>Biblical Peoples and Ethnicity\u00a0: An Archaeological Study of Egyptians, Canaanites, Philistines, and Early Israel, 1300-1100 B.C.E.,<\/i>\u00a0Leiden, Netherlands, Brill, 2005, p. 8.<\/li>\n<li>Catherine Soanes et Angus Stevenson,\u00a0<i>Concise Oxford English Dictionary,<\/i>\u00a0Oxford, Oxford University Press, 2004.<\/li>\n<li>Tzvetan Todorov, \u00ab\u00a0Race and Racism\u00a0\u00bb, dans Les Back et John Solomos, \u00e9ds.,\u00a0<i>Theories of Race and Racism\u00a0: A Reader,<\/i>\u00a0Londres, Routledge, 2000, p. 64-70.<\/li>\n<li>Cashmore, Banton et Adam, p. 254.<\/li>\n<li>Dennis Okholm,\u00a0<i>The Gospel in Black and White\u00a0: Theological Resources for Racial Reconciliation,<\/i>\u00a0Downers Grove, Illinois, InterVarsity Press, 1997, p. 118.<\/li>\n<li>Duane Christensen, \u00ab\u00a0Nations\u00a0\u00bb, \u00e9d. David Noel Freedman,\u00a0<i>The Anchor Bible Dictionary,<\/i>\u00a0New York, Doubleday, 1992, 4, p.1037.<\/li>\n<li>William Arndt, Frederick Danker, et Walter Bauer,\u00a0<i>A Greek-English Lexicon of the New Testament and Other Early Christian Literature,<\/i>\u00a0Chicago, Illinois, University of Chicago Press, 2000, p. 276.<\/li>\n<li><i>Ibid.,<\/i>\u00a0p. 586.<\/li>\n<li>N. Hillyer, \u00ab\u00a0Tribe\u00a0\u00bb, Colin Brown, \u00e9d.\u00a0<i>New International Dictionary of New Testament Theology,<\/i>\u00a0Grand Rapids, Michigan, Zondervan Publishing House, 1986, p. 871.<\/li>\n<li>J. Daniel Hays,\u00a0<i>From Every People and Nation\u00a0: A Biblical Theology of Race,<\/i>\u00a0Downers Grove, Illinois, InterVarsity, 2003, p. 56-60. Voir Frank Cr\u00fcsemann, \u00ab\u00a0Human Solidarity and Ethnic Identity: Israel\u2019s Self-Definition in the Genealogical System of Genesis\u00a0\u00bb, dans Mark G. Brett, \u00e9d.,\u00a0<i>Ethnicity and the Bible,<\/i>\u00a0Leiden, Brill, 1996, p. 197-214.<\/li>\n<li>Jon Levenson, \u00ab\u00a0The Universal Horizon of Biblical Particularism\u00a0\u00bb, dans Mark Brett, \u00e9d.,\u00a0<i>Ethnicity and the Bible,<\/i>\u00a0Leiden, Brill, 1996, p. 147. Voir aussi Reinaldo Siqueira, \u00ab\u00a0The Presence of the Covenant Motif in Amos 1:2-2:16\u00a0\u00bb, th\u00e8se de doctorat, Universit\u00e9 Andrews, 1996.<\/li>\n<li>Keith Ferdinando, \u00ab\u00a0The Ethnic Enemy \u2013 No Greek or Jew \u2026 Barbarian, Scythian\u00a0: The Gospel and Ethnic Difference\u00a0\u00bb,\u00a0<i>Themelios<\/i>\u00a02, septembre 2008, 33, p. 57.<\/li>\n<li><i>Ibid.,<\/i>\u00a0p. 10.<\/li>\n<li>John Oswalt,\u00a0<i>The Book of Isaiah,<\/i>\u00a0chapitres 1-39, Grand Rapids, Michigan, Eerdmans, 1986, p. 381.<\/li>\n<li>Ferdinando, p. 58.<\/li>\n<li>William Storrar, \u00ab\u00a0\u201cVertigo\u201d or \u201cImago\u201d\u00a0? Nations in the Divine Economy\u00a0\u00bb,\u00a0<i>Themelios<\/i>\u00a03, avril 1996, 21, p. 4.<\/li>\n<li>Cette affirmation plut\u00f4t g\u00e9n\u00e9rale n\u2019an\u00e9antit pas les fonctions et distinctions li\u00e9es au sexe (homme et femme) \u00e9tablies \u00e0 la cr\u00e9ation\u00a0; elle confirme plut\u00f4t la restauration de Dieu de la cr\u00e9ation \u00e0 travers l\u2019\u0153uvre de salut de J\u00e9sus.Voir Thomas R. Schreiner,\u00a0<i>Galatians,<\/i>\u00a0Grand Rapids, Michigan, Zondervan, 2010, p. 259.<\/li>\n<li>Voir John Barclay, \u00ab\u00a0\u201cNeither Jew Nor Greek\u201d\u00a0: Multiculturalism and the New Perspective on Paul\u00a0\u00bb, dans Brett, p. 197-214.<\/li>\n<li>Miroslav Volf,\u00a0<i>Exclusion and Embrace\u00a0: A Theological Exploration of Identity, Otherness, and Reconciliation,<\/i>\u00a0Nashville, Tennessee, Abingdon Press, 1996, p. 75. Voir un r\u00e9sum\u00e9 utile dans Ferdinando, p. 59.<\/li>\n<li>Voir R. Knauth, \u00ab\u00a0Alien, Foreign Resident\u00a0\u00bb, dans T. Desmond Alexander et David Baker, \u00e9ds.,\u00a0<i>Dictionary of the Old Testament\u00a0: Pentateuch,<\/i>\u00a0Downers Grove, Illinois, InterVarsity Press, 2003, p. 24-33.<\/li>\n<li>David Benner et Peter Hill, \u00e9ds., \u00ab Baker Encyclopedia of Psychology and Counseling \u00bb, Baker Reference Library, Grand Rapids, Michigan, Baker Books, 1999, p. 896.<!--more--><\/li>\n<\/ol>\n<\/section>\n<\/div>\n<p><\/main><\/p>\n<footer>\n<div class=\"wrapper\"><a href=\"https:\/\/education.adventist.org\/amicus\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a9 Comit\u00e9 pour les \u00e9tudiants et dipl\u00f4m\u00e9s universitaires adventistes (CEDUA)<\/a>, 2014 &#8211; 2019 \u00a0\u00a0|\u00a0\u00a0\u00a0<a href=\"https:\/\/dialogue.adventist.org\/fr\/confidentialite\">Confidentialit\u00e9<\/a><\/div>\n<\/footer>\n","protected":false},"excerpt":{"rendered":"<p>Elias Brasil de Souza Toute manifestation de racisme, d\u2019ethnocentrisme, de nationalisme, de tribalisme ou d\u2019esprit de caste est inacceptable, non seulement d\u2019un point de vue humanitaire, mais aussi d\u2019une perspective biblique. Dans notre monde contemporain, le racisme et le nationalisme demeurent des d\u00e9fis de taille. Malheureusement, ces probl\u00e8mes affectent aussi l\u2019\u00c9glise et invalident son privil\u00e8ge, [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":1214,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[218,222],"tags":[573,572],"aioseo_notices":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/1212"}],"collection":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":0,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media\/1214"}],"wp:attachment":[{"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adventdesk.com\/home\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}